
{"id":10361,"date":"2021-09-25T13:43:00","date_gmt":"2021-09-25T13:43:00","guid":{"rendered":"https:\/\/esperanzaunited.org\/?post_type=cde-knowledge-base&#038;p=10361"},"modified":"2025-08-27T08:54:48","modified_gmt":"2025-08-27T13:54:48","slug":"respeto-de-los-limites","status":"publish","type":"cde-knowledge-base","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/","title":{"rendered":"Respeto de los l\u00edmites"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10361\" class=\"elementor elementor-10361\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c254e65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c254e65\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75c016d3\" data-id=\"75c016d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d0ac298 elementor-widget elementor-widget-text-editor\" data-id=\"4d0ac298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Respeto de los l\u00edmites<\/b><\/h3><p><span style=\"font-weight: 400;\">Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s.<\/span><\/p><h4><b>Establece l\u00edmites<\/b><\/h4><p><span style=\"font-weight: 400;\">Cuando pones l\u00edmites a tus hijos\/as les vas a hacer sentir orden y estabilidad. Por ejemplo, si tu hijo\/a quiere comprar un juego de video violento, es tu derecho y responsabilidad decirle: \u201cNo me gusta el mensaje impl\u00edcito que trasmite ese juego. La violencia no es buena y es da\u00f1ina y, sin embargo, ese juego la presenta como algo divertido. S\u00e9 que lo juegas en casa de Alex, pero no quiero que lo juegues aqu\u00ed\u201d.\u00a0 O, por ejemplo, si tu hijo\/a mayor discute contigo porque no quiere tener una hora l\u00edmite antes de la que tiene que regresar a casa, le puedes decir: \u201cConsidero que esta regla es necesaria para tu seguridad y tu salud. Si s\u00e9 a qu\u00e9 hora vas a volver a casa, enseguida sabr\u00e9 si te ha pasado algo cuando no llegues a esa hora y as\u00ed saldr\u00e9 a buscarte por si has tenido un accidente o si te encuentras en problemas.\u00a0 Adem\u00e1s, mantener un horario fijo asegura que duermas y descanses es una buena forma de asegurar que duermas y descanses suficiente, que comas bien y puedas ocuparte de tus responsabilidades sin que te estreses demasiado.\u201d<\/span><\/p><h4><b>Los l\u00edmites le ense\u00f1an a los\/las ni\u00f1os\/as auto control<\/b><\/h4><p><span style=\"font-weight: 400;\">Cuando estableces l\u00edmites para tus hijos\/as y haces posible que practiquen auto control, aprender\u00e1n que algunos comportamientos son aceptables y otros no. Aprender\u00e1n a lidiar con sentimientos de frustraci\u00f3n cuando no obtienen lo que quieren y aprender\u00e1n a respetar los l\u00edmites de otras personas.\u00a0 Los ni\u00f1os\/as van a poner a prueba y van a resistirse a los l\u00edmites que les pongas, pues esta es de hecho una de las caracter\u00edsticas de la adolescencia, es oponerse a que les pongan l\u00edmites. Sin embargo, si aprenden la importancia de los\u00a0 l\u00edmites, cuando alcancen la madurez ser\u00e1n capaces de establecer l\u00edmites y respetarlos. Supongamos que le has dicho que cuando terminen sus quehaceres dom\u00e9sticos los\/as llevar\u00e1s a la piscina. En vez de completar sus quehaceres deciden ponerse a ver videos y por ello no los\/as llevas a la piscina. Esto va a hacerles ver las consecuencias de sus acciones y van a ver que te respetas pues cumples con tu palabra y no te dejas manipular, manteniendo tu decisi\u00f3n.<\/span><\/p><blockquote><p>Es importante que mantengas presente que el objetivo no debe ser controlar a tus hijos\/as sino que les ense\u00f1es los valores que gu\u00edan tus acciones, normas y principios, lo que esperas de ellos\/as y que sus actos tienen consecuencias. En el ejemplo que acabamos de darte, por ejemplo, aprender\u00e1n que es importante trabajar, que todos\/as en la familia son responsables del cuidado del hogar y que la consecuencia de no haber cumplido con sus responsabilidades fue que no los\/as llevaste a la piscina. Tambi\u00e9n les demostraste que te respetas a ti mismo\/a, tus principios, tu decisi\u00f3n, tus valores e integridad lo suficiente como para cumplir lo que dijiste. De esta manera les transmites que ellos\/as mismos\/as eligen su manera de comportarse y que tendr\u00e1n que responder por las responsabilidades que se les asignan. Esto, no obstante, no es lo mismo que \u2018obligar\u2019 a tu hijo\/a actuar como t\u00fa quieres usando, por ejemplo, rega\u00f1os, amenazas, discusiones o imponiendo castigos.<\/p><\/blockquote><p><span style=\"font-weight: 400;\">Los l\u00edmites deben existir pues crean un \u201cespacio seguro\u201d donde ni\u00f1os\/as y j\u00f3venes tienen la oportunidad de aprender y de poner en pr\u00e1ctica de forma independiente nuevas habilidades. Tus hijos\/as continuar\u00e1n creciendo y desarroll\u00e1ndose as\u00ed como tu relaci\u00f3n con ellos\/as, por lo tanto es normal que tengas que renegociar l\u00edmites, que se resistan a los mismos y que tal vez los tengas que cambiar si lo consideras necesario.<\/span><\/p><h4><b>Ens\u00e9\u00f1ales a poner sus l\u00edmites<\/b><\/h4><p><span style=\"font-weight: 400;\">Ens\u00e9\u00f1ales que en una relaci\u00f3n cada persona decide qu\u00e9 quiere y qu\u00e9 no quiere.\u00a0 Aprovecha durante actividades diarias para hablarles. Por ejemplo, si tienes hijos\/as peque\u00f1os\/as puedes decirles a la hora del ba\u00f1o que sus partes privadas les pertenecen solo a ellos\/as y que nadie debe tocarlas a menos que sea por razones de higiene (para que sean limpiadas) o por razones de salud (si necesitan ser examinadas).<\/span><\/p><p><span style=\"font-weight: 400;\">Ayuda a tus hijos\/as a entender la importancia de que se sientan libres de hablar sobre sus l\u00edmites personales y establecerlos sin miedo a que por ello se les reprima de alg\u00fan modo, y ens\u00e9\u00f1ales que sus l\u00edmites deben ser siempre respetados. Crea oportunidades que les permita meditar sobre esto y analizarlo con cuidado. Por ejemplo, les puedes preguntar: \u201cYa que tu hermana y t\u00fa comparten la misma habitaci\u00f3n, \u00bfde qu\u00e9 manera crees ustedes pueden hacer posible que cada una tenga su privacidad y que la privacidad de cada una sea respetada?\u201d<\/span><\/p><p><span style=\"font-weight: 400;\">Hazles saber que nadie tiene derecho de demandar, forzar, exigir ni esperar que ellos\/as les deben nada. Que, por ejemplo,\u00a0 de la misma manera que cuando eran peque\u00f1os\/as se negaban a darle un beso o un abrazo a alg\u00fan miembro de la familia si no quer\u00edan hacerlo; que tampoco deben sentirse obligados\/as a hacerlo con un\/a novio\/a o alguien con quien est\u00e9n saliendo si no quieren, y que nadie les debe presionar para que tengan sexo.<\/span><\/p><h4><b>Ens\u00e9\u00f1ales a respetar los l\u00edmites de otras personas<\/b><\/h4><p><span style=\"font-weight: 400;\">Una forma de mostrarle a tus hijos\/as tu respeto por ellos\/as es dej\u00e1ndoles elegir y tomar sus propias decisiones dentro de marcos saludables, reconociendo y aceptando su elecci\u00f3n.<\/span><\/p><p><span style=\"font-weight: 400;\">De forma general, hay ciertas cosas que t\u00fa les puedes ense\u00f1ar para que aprendan a respetar los l\u00edmites de otras personas, y todas estas cosas est\u00e1n relacionadas:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ens\u00e9\u00f1ales sobre los l\u00edmites personales y la importancia de que estos sean respetados<\/span><\/span>\u00a0<\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ens\u00e9\u00f1ales a comunicarse de manera directa y sincera<\/span><\/span>\u00a0<\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Respeta los l\u00edmites<br \/>personales de tus hijos\/as<\/span><\/span>\u00a0<\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Establece l\u00edmites para tus hijos\/as que sean l\u00f3gicos y necesarios<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">S\u00e9 un ejemplo de buen comportamiento: Establece tus propios l\u00edmites, respeta los l\u00edmites de otras personas y asume responsabilidad por tus propias acciones y emociones.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba73725 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba73725\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6188764\" data-id=\"6188764\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-039af44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"039af44\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c6d96fd\" data-id=\"c6d96fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65b7f78 elementor-align-left view-more-post elementor-widget elementor-widget-button\" data-id=\"65b7f78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.decimosnomas.org\/profundiza\/relaciones-saludables\/como-lidiamos-con-conflictos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8e8d245\" data-id=\"8e8d245\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a09ef8 elementor-widget elementor-widget-text-editor\" data-id=\"6a09ef8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Sigue leyendo: <\/b><a href=\"https:\/\/www.decimosnomas.org\/profundiza\/relaciones-saludables\/como-lidiamos-con-conflictos\/\"><b>C\u00f3mo lidiamos con conflictos.<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62cb83c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62cb83c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26d05b3\" data-id=\"26d05b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5e00fa elementor-widget elementor-widget-text-editor\" data-id=\"a5e00fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span style=\"font-weight: 400;\">1. Ve a <\/span><a href=\"https:\/\/www.empoweringparents.com\/article\/punishments-vs-consequences-which-are-you-using\"><span style=\"font-weight: 400;\">Punishments vs. consequences: Which are you using?<\/span><\/a><span style=\"font-weight: 400;\"> por Empowering Parents.<\/span><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e66013 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e66013\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15e34f2\" data-id=\"15e34f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0d5c13 elementor-widget elementor-widget-text-editor\" data-id=\"c0d5c13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>\u00a0<\/div><div style=\"text-align: right;\"><span style=\"font-weight: 200;\">\u00daltima actualizaci\u00f3n 2021<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Respeto de los l\u00edmites Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s. Establece l\u00edmites Cuando pones l\u00edmites a tus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_cbd_carousel_blocks":"[]"},"media_category":[250,251],"media_tags":[290,306,590],"class_list":["post-10361","cde-knowledge-base","type-cde-knowledge-base","status-publish","hentry","media_category-kits-de-herramientas","media_category-decimos-no-mas","media_tags-gratis","media_tags-prevencion","media_tags-recursos-para-jovenes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Respeto de los l\u00edmites Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s. Establece l\u00edmites Cuando pones l\u00edmites a tus hijos\/as les vas a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Manish\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Respeto de los l\u00edmites - Esperanza United\" \/>\n\t\t<meta property=\"og:description\" content=\"Respeto de los l\u00edmites Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s. Establece l\u00edmites Cuando pones l\u00edmites a tus hijos\/as les vas a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-25T13:43:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-27T13:54:48+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Respeto de los l\u00edmites - Esperanza United\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Respeto de los l\u00edmites Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s. Establece l\u00edmites Cuando pones l\u00edmites a tus hijos\/as les vas a\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/decimos-no-mas\\\/respeto-de-los-limites\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"name\":\"Knowledge Base\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"position\":2,\"name\":\"Knowledge Base\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"name\":\"Kits de herramientas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"position\":3,\"name\":\"Kits de herramientas\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/decimos-no-mas\\\/#listItem\",\"name\":\"Decimos NO M\\u00c1S\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"name\":\"Knowledge Base\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/decimos-no-mas\\\/#listItem\",\"position\":4,\"name\":\"Decimos NO M\\u00c1S\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/decimos-no-mas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/decimos-no-mas\\\/respeto-de-los-limites\\\/#listItem\",\"name\":\"Respeto de los l\\u00edmites\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"name\":\"Kits de herramientas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/decimos-no-mas\\\/respeto-de-los-limites\\\/#listItem\",\"position\":5,\"name\":\"Respeto de los l\\u00edmites\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/decimos-no-mas\\\/#listItem\",\"name\":\"Decimos NO M\\u00c1S\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/\",\"name\":\"Manish\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/decimos-no-mas\\\/respeto-de-los-limites\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54c203425d096cb9d4ecf6f339772103c5a7fb592c84c1599a524e3921ba945a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Manish\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/decimos-no-mas\\\/respeto-de-los-limites\\\/#webpage\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/decimos-no-mas\\\/respeto-de-los-limites\\\/\",\"name\":\"Respeto de los l\\u00edmites - Esperanza United\",\"description\":\"Respeto de los l\\u00edmites Cuando hablas con tus hijos\\\/as sobre la importancia de respetar l\\u00edmites, les est\\u00e1s ense\\u00f1ando algo muy importante que les dar\\u00e1 una idea general de lo que son los l\\u00edmites, y a entender el respeto a uno mismo y los dem\\u00e1s. Establece l\\u00edmites Cuando pones l\\u00edmites a tus hijos\\\/as les vas a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/decimos-no-mas\\\/respeto-de-los-limites\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\"},\"datePublished\":\"2021-09-25T13:43:00-05:00\",\"dateModified\":\"2025-08-27T08:54:48-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Respeto de los l\u00edmites - Esperanza United","description":"Respeto de los l\u00edmites Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s. Establece l\u00edmites Cuando pones l\u00edmites a tus hijos\/as les vas a","canonical_url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/esperanzaunited.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","name":"Knowledge Base"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","position":2,"name":"Knowledge Base","item":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","name":"Kits de herramientas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","position":3,"name":"Kits de herramientas","item":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/decimos-no-mas\/#listItem","name":"Decimos NO M\u00c1S"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","name":"Knowledge Base"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/decimos-no-mas\/#listItem","position":4,"name":"Decimos NO M\u00c1S","item":"https:\/\/esperanzaunited.org\/es\/media_category\/decimos-no-mas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/#listItem","name":"Respeto de los l\u00edmites"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","name":"Kits de herramientas"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/#listItem","position":5,"name":"Respeto de los l\u00edmites","previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/decimos-no-mas\/#listItem","name":"Decimos NO M\u00c1S"}}]},{"@type":"Organization","@id":"https:\/\/esperanzaunited.org\/es\/#organization","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","url":"https:\/\/esperanzaunited.org\/es\/"},{"@type":"Person","@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author","url":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/","name":"Manish","image":{"@type":"ImageObject","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/54c203425d096cb9d4ecf6f339772103c5a7fb592c84c1599a524e3921ba945a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Manish"}},{"@type":"WebPage","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/#webpage","url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/","name":"Respeto de los l\u00edmites - Esperanza United","description":"Respeto de los l\u00edmites Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s. Establece l\u00edmites Cuando pones l\u00edmites a tus hijos\/as les vas a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/#breadcrumblist"},"author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author"},"creator":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author"},"datePublished":"2021-09-25T13:43:00-05:00","dateModified":"2025-08-27T08:54:48-05:00"},{"@type":"WebSite","@id":"https:\/\/esperanzaunited.org\/es\/#website","url":"https:\/\/esperanzaunited.org\/es\/","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","inLanguage":"es-ES","publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence","og:type":"article","og:title":"Respeto de los l\u00edmites - Esperanza United","og:description":"Respeto de los l\u00edmites Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s. Establece l\u00edmites Cuando pones l\u00edmites a tus hijos\/as les vas a","og:url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/","article:published_time":"2021-09-25T13:43:00+00:00","article:modified_time":"2025-08-27T13:54:48+00:00","twitter:card":"summary","twitter:title":"Respeto de los l\u00edmites - Esperanza United","twitter:description":"Respeto de los l\u00edmites Cuando hablas con tus hijos\/as sobre la importancia de respetar l\u00edmites, les est\u00e1s ense\u00f1ando algo muy importante que les dar\u00e1 una idea general de lo que son los l\u00edmites, y a entender el respeto a uno mismo y los dem\u00e1s. Establece l\u00edmites Cuando pones l\u00edmites a tus hijos\/as les vas a"},"aioseo_meta_data":{"post_id":"10361","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-63e6a2d0a99a5","slug":"web-page","graphName":"WebPage","label":"P\u00e1gina web","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-25 13:43:00","updated":"2025-11-22 03:55:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/\" title=\"Knowledge Base\">Knowledge Base<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/\" title=\"Kits de herramientas\">Kits de herramientas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/media_category\/decimos-no-mas\/\" title=\"Decimos NO M\u00c1S\">Decimos NO M\u00c1S<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRespeto de los l\u00edmites\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esperanzaunited.org\/es\/"},{"label":"Knowledge Base","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/"},{"label":"Kits de herramientas","link":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/"},{"label":"Decimos NO M\u00c1S","link":"https:\/\/esperanzaunited.org\/es\/media_category\/decimos-no-mas\/"},{"label":"Respeto de los l\u00edmites","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/decimos-no-mas\/respeto-de-los-limites\/"}],"_links":{"self":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base"}],"about":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/types\/cde-knowledge-base"}],"author":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":20,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10361\/revisions"}],"predecessor-version":[{"id":36764,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10361\/revisions\/36764"}],"wp:attachment":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media?parent=10361"}],"wp:term":[{"taxonomy":"media_category","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media_category?post=10361"},{"taxonomy":"media_tags","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media_tags?post=10361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}