
{"id":10396,"date":"2021-09-25T14:53:52","date_gmt":"2021-09-25T14:53:52","guid":{"rendered":"https:\/\/esperanzaunited.org\/?post_type=cde-knowledge-base&#038;p=10396"},"modified":"2025-08-27T09:09:49","modified_gmt":"2025-08-27T14:09:49","slug":"como-evaluar-un-programa","status":"publish","type":"cde-knowledge-base","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/","title":{"rendered":"\u00bfC\u00f3mo evaluar un programa?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10396\" class=\"elementor elementor-10396\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c73c1ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c73c1ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf57914\" data-id=\"cf57914\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3acefd0 elementor-widget elementor-widget-text-editor\" data-id=\"3acefd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>\u00bfC\u00f3mo evaluar un programa?<\/strong><\/h3><p>Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la informaci\u00f3n, y luego la transformas. Para poder transformar esta informaci\u00f3n t\u00fa necesitas aprender c\u00f3mo organizarla, analizarla, e interpretar los datos.\u00a0 En esta secci\u00f3n vamos a revisar ese proceso.\u00a0\u00a0<\/p><p>Probablemente ya re\u00fanes una enorme cantidad de informaci\u00f3n acerca de tu programa. Por ejemplo, informaci\u00f3n acerca de qui\u00e9n est\u00e1 usando tus servicios y a cuantas personas ven cada d\u00eda. Esta informaci\u00f3n se le llama datos en bruto o crudos. Para hacer que estos datos brutos sean \u00fatiles\u00a0 tienes que transformarlos en informaci\u00f3n que tenga significado a trav\u00e9s de la organizaci\u00f3n, an\u00e1lisis e interpretaci\u00f3n de los mismos.\u00a0 Estos datos brutos pueden ser en forma de n\u00fameros (lo que denominamos datos cuantitativos) o palabras (lo que denominamos datos cualitativos).\u00a0\u00a0<\/p><h4>Datos cuantitativos<\/h4><p>El primer paso es <b>organizar <\/b>los datos de una manera en la que sea f\u00e1cil entender y encontrarlos.<\/p><p>Podr\u00edamos pedirles a los participantes\u00a0 que\u00a0 llenen una encuesta y que nos digan cu\u00e1l es su edad, genero, lugar de origen, etc. Para <b>organizar <\/b>estos datos en una manera de que podamos entenderlos y encontrarlos f\u00e1cilmente, entramos los datos (informaci\u00f3n) de cada encuesta en una tabla en Word o en una hoja de c\u00e1lculo en Excel.<\/p><p>Aqu\u00ed tienes un <a href=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Demographic-Intake-form.pdf\">ejemplo<\/a> de una tabla que creamos utilizando datos cuantitativos (n\u00fameros) con los participantes de la encuesta:<\/p><p><a href=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Demographic-Intake-form.pdf\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-27703\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Screen-Shot-2024-05-06-at-11.09.29-AM-231x300.png\" alt=\"\" width=\"231\" height=\"300\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Screen-Shot-2024-05-06-at-11.09.29-AM-231x300.png 231w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Screen-Shot-2024-05-06-at-11.09.29-AM-790x1024.png 790w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Screen-Shot-2024-05-06-at-11.09.29-AM-768x995.png 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Screen-Shot-2024-05-06-at-11.09.29-AM-600x778.png 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Screen-Shot-2024-05-06-at-11.09.29-AM.png 1020w\" sizes=\"(max-width: 231px) 100vw, 231px\" \/><\/a><\/p><p><a href=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/05\/Demographic-Intake-form.pdf\">Esperanza United Demographic form<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a50a014 covid-resource-table elementor-widget elementor-widget-pafe-table\" data-id=\"a50a014\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pafe-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pafe-table-container\" >\n\t\t\t<div class=\"pafe-table-inner table_center\">\n\t\t\t\t<table class=\"pafe-table\">\n\t\t\t\t\t\t\t\t\t\t\t<thead class=\"pafe-table-head\">\n\t\t\t\t\t\t\t<tr class=\"pafe-table-head-row\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-head-cell center\" colspan=\"1\" style=\"width: 100px;\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-content\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-text\">N\u00famero de participantes<\/span>\n\t\t\t\t\t\t\t\t\t\t<!-- \t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-sort fa fa-sort\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-down fa fa-sort-desc\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-up fa fa-sort-asc\"aria-hidden=\"true\" ><\/i> -->\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-head-cell left\" colspan=\"1\" style=\"width: 100px;\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-content\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-text\">Edad<\/span>\n\t\t\t\t\t\t\t\t\t\t<!-- \t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-sort fa fa-sort\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-down fa fa-sort-desc\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-up fa fa-sort-asc\"aria-hidden=\"true\" ><\/i> -->\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-head-cell left\" colspan=\"1\" style=\"width: 100px;\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-content\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-text\">Sexo\/g\u00e9nero<\/span>\n\t\t\t\t\t\t\t\t\t\t<!-- \t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-sort fa fa-sort\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-down fa fa-sort-desc\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-up fa fa-sort-asc\"aria-hidden=\"true\" ><\/i> -->\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-head-cell left\" colspan=\"1\" style=\"width: 100px;\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-content\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-text\">Lugar de origen<\/span>\n\t\t\t\t\t\t\t\t\t\t<!-- \t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-sort fa fa-sort\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-down fa fa-sort-desc\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-up fa fa-sort-asc\"aria-hidden=\"true\" ><\/i> -->\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-head-cell left\" colspan=\"1\" style=\"width: 100px;\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-content\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-text\">Promedio de a\u00f1os de domicilio<\/span>\n\t\t\t\t\t\t\t\t\t\t<!-- \t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-sort fa fa-sort\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-down fa fa-sort-desc\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-up fa fa-sort-asc\"aria-hidden=\"true\" ><\/i> -->\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-head-cell left\" colspan=\"1\" style=\"width: 100px;\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-content\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-text\">A\u00f1os de educaci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t\t<!-- \t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-sort fa fa-sort\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-down fa fa-sort-desc\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-up fa fa-sort-asc\"aria-hidden=\"true\" ><\/i> -->\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-head-cell left\" colspan=\"1\" style=\"width: 100px;\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-content\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-head-text\">N\u00famero de actividades a las que atiende en el a\u00f1o<\/span>\n\t\t\t\t\t\t\t\t\t\t<!-- \t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-sort fa fa-sort\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-down fa fa-sort-desc\"aria-hidden=\"true\" ><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"pafe-table-head-item-icon pafe-table-head-item-icon-up fa fa-sort-asc\"aria-hidden=\"true\" ><\/i> -->\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\t\n\t\t\t\t\t\t<\/thead>\n\t\t\t\t\t\t<tbody class=\"pafe-table-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >1<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >32<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >Hombre<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >Minneapolis<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >9.7<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >6<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >2<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t <\/tr> <tr class=\"pafe-table-body-row\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t <\/tr> <tr class=\"pafe-table-body-row\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-body-first-cell left\" rowspan=\"1\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-first-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-first-text\">2<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >48<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >Mujer<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >Saint Paul<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >11.6<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >10<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >5<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t <\/tr> <tr class=\"pafe-table-body-row\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th class=\"pafe-table-body-first-cell left\" rowspan=\"1\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-first-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-first-text\">3<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >40<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >Hombre<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >Chaska<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >7.5<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >12<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"pafe-table-body-cell left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pafe-table-body-content\">\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pafe-table-body-text\" >3<\/a>\n                                                    \t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t<\/tbody>\n\t\t\t\t\t\t\t\t\t<\/table>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-341cace elementor-widget elementor-widget-text-editor\" data-id=\"341cace\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Esta tabla nos permite de una manera m\u00e1s f\u00e1cil ver toda la informaci\u00f3n que hemos reunido. Si no hubi\u00e9ramos creado esta tabla tendr\u00edamos que leer todas las encuestas cada vez que quisi\u00e9ramos aprender algo de nuestros participantes\/clientes.\u00a0\u00a0<\/span><\/p><h5><strong>An\u00e1lisis de los datos cuantitativos<\/strong><\/h5><p><span style=\"font-weight: 400;\">El pr\u00f3ximo paso es <\/span><b>analizar <\/b><span style=\"font-weight: 400;\">los datos de manera que podamos obtener informaci\u00f3n que nos dice algo que quer\u00edamos saber.<\/span><\/p><p><b>Por ejemplo<\/b><span style=\"font-weight: 400;\">, podemos <\/span><b>analizar <\/b><span style=\"font-weight: 400;\">los datos de la tabla que hicimos de los participantes en la encuesta para que nos diga algo acerca de las personas que utilizan nuestros servicios. Las formas m\u00e1s comunes del an\u00e1lisis de los datos incluyen el conteo de frecuencia y el promedio. <\/span><\/p><h6>An\u00e1lisis de la muestra<\/h6><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">3 participantes (Conteo de frecuencia)<\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">40 a\u00f1os\u00a0 (Edad promedio)<\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">1 mujer y 2 hombres (Conteo de frecuencia)<\/span><\/li><\/ul><h5><span style=\"font-weight: 400;\">Interpretaci\u00f3n de los datos cuantitativos<\/span><\/h5><p><span style=\"font-weight: 400;\">El siguiente paso es interpretar los datos de manera que sean \u00fatiles para nosotros.<\/span><\/p><h6>An\u00e1lisis de la muestra<\/h6><p><span style=\"font-weight: 400;\">Se observa que de l@s tres participantes la edad promedio es 40 a\u00f1os, y que tenemos m\u00e1s participantes hombres que participantes mujeres.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Como puedes ver, pudimos transformar los datos brutos que ten\u00edamos en la tabla en un p\u00e1rrafo breve que nos ofrece informaci\u00f3n significativa acerca de los participantes\u00a0 en el programa. Ahora veamos c\u00f3mo transformamos los datos cualitativos en bruto (palabras).<\/span><\/p><h4><b>Datos cualitativos<\/b><\/h4><p><span style=\"font-weight: 400;\">La mayor\u00eda de los datos cualitativos (palabras) que recolectamos provienen de las grabaciones de entrevistas o de las conversaciones en los grupos focales. Otras veces utilizamos los datos de las notas ya sea del personal o de l@s participantes que colectamos acerca del programa o de alguna actividad espec\u00edfica del programa.<\/span><\/p><p><span style=\"font-weight: 400;\">Al igual que con los datos cuantitativos, el primer paso es <\/span><b>organizar <\/b><span style=\"font-weight: 400;\">los datos. Con los datos cualitativos esto quiere decir que necesitamos transcribir la informaci\u00f3n de la grabaci\u00f3n a un documento en Word o las notas escritas a mano a un documento en Word. Esto te permite tener toda la informaci\u00f3n en un mismo formato para que puedas analizarla.\u00a0<\/span><\/p><h5><strong>An\u00e1lisis de los datos cualitativos<\/strong><\/h5><p><span style=\"font-weight: 400;\">El siguiente paso es el <\/span><b>an\u00e1lisis <\/b><span style=\"font-weight: 400;\">de los datos y que consiste en identificar los temas principales o sobresalientes.\u00a0 La siguiente gu\u00eda de paso a paso te servir\u00e1 de ayuda en este proceso:<\/span><\/p><ol><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Primero, debes escribir todas tus observaciones acerca de la actividad, y de los temas o asuntos que t\u00fa recuerdas.<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lo siguiente es revisar tus notas y\/o las transcripciones. Comienza por subrayar y darle una etiqueta o t\u00edtulo a estos temas. <\/span><b>Por ejemplo<\/b><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">, si t\u00fa notas que varios temas tienen que ver con la manera efectiva de involucrar a la comunidad, una etiqueta puede ser participaci\u00f3n de la comunidad.<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Repet\u00ed este mismo proceso con el resto de la informaci\u00f3n que hayas acumulado.<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">A la largo que etiquetas los temas, tu empezaras a notar que los temas se repiten (esto es lo que denominamos temas repetidos).<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lo siguiente es colocar junto todos los temas que son similares. Quiz\u00e1s tendr\u00e1s que unir varios temas para reducir los resultados a una cantidad que sea manejable.\u00a0<br \/>\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Esta lista de temas es el resultado de tu an\u00e1lisis.<\/span><\/li><\/ol><p><span style=\"font-weight: 400;\">Ahora veamos un ejemplo. Esta muestra de un tema fue obtenida de una actividad con un grupo focal de j\u00f3venes acerca del programa de la Acci\u00f3n Diferida para los llegados en la Infancia (DACA).<\/span><\/p><p><span style=\"font-weight: 400;\">\u201cDACA me ha permitido ingresar a la universidad en otro estado. Sin DACA yo nunca hubiera aplicado a una universidad lejos de casa, porque yo sab\u00eda que no pod\u00eda viajar con seguridad alrededor del pa\u00eds dado a la situaci\u00f3n con mis papeles.\u201d<\/span><\/p><p><span style=\"font-weight: 400;\">De estas oraciones pudimos identificar los siguientes temas:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">TEMA: Aumento de las oportunidades de educaci\u00f3n<\/span><\/span><\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">DACA expandi\u00f3 el n\u00famero de universidades a las que l@s j\u00f3venes pueden aplicar<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">DACA le permite a l@s j\u00f3venes considerar m\u00e1s oportunidades educacionales<\/span><\/span><\/span><\/li><\/ul><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">TEMA: Seguridad<\/span><\/span><\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">El programa protege a l@s j\u00f3venes sin importar su situaci\u00f3n migratoria<\/span><\/li><\/ul><\/li><\/ul><h5>Interpretaci\u00f3n de los datos cualitativos<\/h5><p><span style=\"font-weight: 400;\">El paso final es la <\/span><b>interpretaci\u00f3n <\/b><span style=\"font-weight: 400;\">de los datos (deducir el significado de los datos).<\/span><\/p><h6>An\u00e1lisis de la muestra<\/h6><p><i><span style=\"font-weight: 400;\">Del testimonio de uno de l@s participantes, nos fue posible aprender acerca del impacto positivo que la implementaci\u00f3n de la Acci\u00f3n Diferida para los llegados en la Infancia, tambi\u00e9n conocida como DACA ha tenido en la vida de l@s j\u00f3venes participantes al abrirles m\u00e1s puertas para oportunidades educativas y aumentar la sensaci\u00f3n de seguridad.\u00a0<\/span><\/i><\/p><p><span style=\"font-weight: 400;\">Este trabajo puede ser una gran oportunidad para incrementar la capacidad de tu personal, l@s l\u00edderes comunales, o\/y organizaciones aliados a trav\u00e9s de su involucraci\u00f3n en el proceso.\u00a0\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afa035f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afa035f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a14efe3\" data-id=\"a14efe3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ed394a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed394a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0748a21\" data-id=\"0748a21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-deb5d81 elementor-align-left view-more-post elementor-widget elementor-widget-button\" data-id=\"deb5d81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/trabajando-con-evaluadores-externos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-10f93b5\" data-id=\"10f93b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c71124 elementor-widget elementor-widget-text-editor\" data-id=\"0c71124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Si t\u00fa no tienes una persona en tu personal que pueda llevar a cabo este proceso, debes considerar la posibilidad de contratar un evaluador externo. Para informaci\u00f3n que te puede guiar en ese proceso por favor visita<\/span><a href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/trabajando-con-evaluadores-externos\/\"><b> la secci\u00f3n Evaluadores externos.<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d776e53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d776e53\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f3e5f1a\" data-id=\"f3e5f1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f84fc9b elementor-widget elementor-widget-text-editor\" data-id=\"f84fc9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><\/div>\n<div style=\"text-align: right;\"><span style=\"font-weight: 200;\">\u00daltima actualizaci\u00f3n 2024<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18469,"template":"","meta":{"_cbd_carousel_blocks":"[]"},"media_category":[321,250,252],"media_tags":[290,285],"class_list":["post-10396","cde-knowledge-base","type-cde-knowledge-base","status-publish","has-post-thumbnail","hentry","media_category-esperanza-united-departamentos","media_category-kits-de-herramientas","media_category-construccion-de-evidencia","media_tags-gratis","media_tags-investigacion-y-evaluacion"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00bfC\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la informaci\u00f3n, y luego la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Manish\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfC\u00f3mo evaluar un programa? - Esperanza United\" \/>\n\t\t<meta property=\"og:description\" content=\"\u00bfC\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la informaci\u00f3n, y luego la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3-1.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-25T14:53:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-27T14:09:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfC\u00f3mo evaluar un programa? - Esperanza United\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u00bfC\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la informaci\u00f3n, y luego la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3-1.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"name\":\"Knowledge Base\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"position\":2,\"name\":\"Knowledge Base\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"name\":\"Kits de herramientas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"position\":3,\"name\":\"Kits de herramientas\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/construccion-de-evidencia\\\/#listItem\",\"name\":\"Construcci\\u00f3n de evidencia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"name\":\"Knowledge Base\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/construccion-de-evidencia\\\/#listItem\",\"position\":4,\"name\":\"Construcci\\u00f3n de evidencia\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/construccion-de-evidencia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/#listItem\",\"name\":\"\\u00bfC\\u00f3mo evaluar un programa?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"name\":\"Kits de herramientas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/#listItem\",\"position\":5,\"name\":\"\\u00bfC\\u00f3mo evaluar un programa?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/construccion-de-evidencia\\\/#listItem\",\"name\":\"Construcci\\u00f3n de evidencia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/\",\"name\":\"Manish\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54c203425d096cb9d4ecf6f339772103c5a7fb592c84c1599a524e3921ba945a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Manish\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/#webpage\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/\",\"name\":\"\\u00bfC\\u00f3mo evaluar un programa? - Esperanza United\",\"description\":\"\\u00bfC\\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\\u00f3n, t\\u00fa inicias por decidir qu\\u00e9 tipo de evaluaci\\u00f3n vas a llevar a cabo, juntas la informaci\\u00f3n, y luego la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3-1.png\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/#mainImage\",\"width\":1080,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/construccion-de-evidencia\\\/como-evaluar-un-programa\\\/#mainImage\"},\"datePublished\":\"2021-09-25T14:53:52-05:00\",\"dateModified\":\"2025-08-27T09:09:49-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfC\u00f3mo evaluar un programa? - Esperanza United","description":"\u00bfC\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la informaci\u00f3n, y luego la","canonical_url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/esperanzaunited.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","name":"Knowledge Base"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","position":2,"name":"Knowledge Base","item":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","name":"Kits de herramientas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","position":3,"name":"Kits de herramientas","item":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/construccion-de-evidencia\/#listItem","name":"Construcci\u00f3n de evidencia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","name":"Knowledge Base"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/construccion-de-evidencia\/#listItem","position":4,"name":"Construcci\u00f3n de evidencia","item":"https:\/\/esperanzaunited.org\/es\/media_category\/construccion-de-evidencia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/#listItem","name":"\u00bfC\u00f3mo evaluar un programa?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","name":"Kits de herramientas"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/#listItem","position":5,"name":"\u00bfC\u00f3mo evaluar un programa?","previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/construccion-de-evidencia\/#listItem","name":"Construcci\u00f3n de evidencia"}}]},{"@type":"Organization","@id":"https:\/\/esperanzaunited.org\/es\/#organization","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","url":"https:\/\/esperanzaunited.org\/es\/"},{"@type":"Person","@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author","url":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/","name":"Manish","image":{"@type":"ImageObject","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/54c203425d096cb9d4ecf6f339772103c5a7fb592c84c1599a524e3921ba945a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Manish"}},{"@type":"WebPage","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/#webpage","url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/","name":"\u00bfC\u00f3mo evaluar un programa? - Esperanza United","description":"\u00bfC\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la informaci\u00f3n, y luego la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/#breadcrumblist"},"author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author"},"creator":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3-1.png","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/#mainImage","width":1080,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/#mainImage"},"datePublished":"2021-09-25T14:53:52-05:00","dateModified":"2025-08-27T09:09:49-05:00"},{"@type":"WebSite","@id":"https:\/\/esperanzaunited.org\/es\/#website","url":"https:\/\/esperanzaunited.org\/es\/","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","inLanguage":"es-ES","publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence","og:type":"article","og:title":"\u00bfC\u00f3mo evaluar un programa? - Esperanza United","og:description":"\u00bfC\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la informaci\u00f3n, y luego la","og:url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/","og:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3-1.png","og:image:secure_url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3-1.png","og:image:width":1080,"og:image:height":1080,"article:published_time":"2021-09-25T14:53:52+00:00","article:modified_time":"2025-08-27T14:09:49+00:00","twitter:card":"summary","twitter:title":"\u00bfC\u00f3mo evaluar un programa? - Esperanza United","twitter:description":"\u00bfC\u00f3mo evaluar un programa? Como hemos mencionado en las sesiones anteriores evaluar un programa es como cocinar. T\u00fa empiezas por seleccionar la receta, reunir los ingredientes, y luego los transformas en una deliciosa comida. En evaluaci\u00f3n, t\u00fa inicias por decidir qu\u00e9 tipo de evaluaci\u00f3n vas a llevar a cabo, juntas la informaci\u00f3n, y luego la","twitter:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3-1.png"},"aioseo_meta_data":{"post_id":"10396","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-63e687a931545","slug":"web-page","graphName":"WebPage","label":"P\u00e1gina web","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-25 14:53:53","updated":"2025-11-22 03:57:00","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/\" title=\"Knowledge Base\">Knowledge Base<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/\" title=\"Kits de herramientas\">Kits de herramientas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/media_category\/construccion-de-evidencia\/\" title=\"Construcci\u00f3n de evidencia\">Construcci\u00f3n de evidencia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfC\u00f3mo evaluar un programa?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esperanzaunited.org\/es\/"},{"label":"Knowledge Base","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/"},{"label":"Kits de herramientas","link":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/"},{"label":"Construcci\u00f3n de evidencia","link":"https:\/\/esperanzaunited.org\/es\/media_category\/construccion-de-evidencia\/"},{"label":"\u00bfC\u00f3mo evaluar un programa?","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/construccion-de-evidencia\/como-evaluar-un-programa\/"}],"_links":{"self":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base"}],"about":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/types\/cde-knowledge-base"}],"author":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":35,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10396\/revisions"}],"predecessor-version":[{"id":36796,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10396\/revisions\/36796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media\/18469"}],"wp:attachment":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media?parent=10396"}],"wp:term":[{"taxonomy":"media_category","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media_category?post=10396"},{"taxonomy":"media_tags","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media_tags?post=10396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}