
{"id":10621,"date":"2021-09-26T09:16:57","date_gmt":"2021-09-26T09:16:57","guid":{"rendered":"https:\/\/esperanzaunited.org\/?post_type=cde-knowledge-base&#038;p=10621"},"modified":"2025-08-27T09:51:13","modified_gmt":"2025-08-27T14:51:13","slug":"ejercicio-1-conocer-a-freddy","status":"publish","type":"cde-knowledge-base","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/","title":{"rendered":"Ejercicio 1: Conocer a Freddy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10621\" class=\"elementor elementor-10621\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f5e0bd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f5e0bd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73b48ea4\" data-id=\"73b48ea4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d31d4e1 elementor-widget elementor-widget-text-editor\" data-id=\"3d31d4e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Ejercicio 1: Conocer a Freddy<\/strong><\/h3><p><span style=\"font-weight: 400;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-9711 alignleft\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/MG_4605_1-Freddy-600x900-1-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/MG_4605_1-Freddy-600x900-1-200x300.jpg 200w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/MG_4605_1-Freddy-600x900-1.jpg 600w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\u00a1Hola! Me llamo Freddy y vivo con mis padres en el <\/span><i><span style=\"font-weight: 400;\">Westside<\/span><\/i><span style=\"font-weight: 400;\"> de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos de mi casa. Tambi\u00e9n tengo varios t\u00edos, t\u00edas, primos y primas en esta zona. Casi todos los domingos nos juntamos para almorzar juntos; a veces, somos m\u00e1s de cuarenta familiares.<\/span><a id=\"glossary_1\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/como\/#family_1\"><b>[i]<\/b><\/a><\/p><p><span style=\"font-weight: 400;\">Hace unos meses, durante uno de los almuerzos domingueros en mi casa, me di cuenta de que mi cu\u00f1ada Blanca estaba llorando sola en la cocina. Le pregunt\u00e9 qu\u00e9 le pasaba, pero no quiso decirme. Le avis\u00e9 a mi mam\u00e1 y se encerraron a platicar en la habitaci\u00f3n. Blanca le tiene mucha confianza<\/span><a id=\"glossary_2\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/como\/#family_2\"><b>[ii]<\/b><\/a><span style=\"font-weight: 400;\"> a mi mam\u00e1 y le cont\u00f3 que mi hermano Jorge le hab\u00eda pegado esa ma\u00f1ana. Le dijo que no era la primera vez y que adem\u00e1s frecuentemente la insultaba y la degradaba, incluso delante de sus hijos.<\/span><\/p><p><span style=\"font-weight: 400;\">Cuando se fueron los familiares, mi mam\u00e1 nos cont\u00f3 a mi pap\u00e1 y a m\u00ed sobre la situaci\u00f3n. Jorge es el hijo del primer esposo de mi mam\u00e1 y ella le tiene miedo porque sabe que tiene mal car\u00e1cter. Mi mam\u00e1 le pidi\u00f3 a mi pap\u00e1 que hablara con Jorge, pero \u00e9l dijo que ya lo hab\u00eda tratado de hacer muchas veces y que adem\u00e1s, era un problema de su familia.<\/span><\/p><p><span style=\"font-weight: 400;\">Jorge se cri\u00f3 con su padre, que es muy machista.<\/span><a id=\"glossary_3\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/como\/#family_3\"><b>[iii]<\/b><\/a><span style=\"font-weight: 400;\"> Quiz\u00e1 ah\u00ed es donde aprendi\u00f3 a ser dominante y violento con las mujeres. Por suerte, mi pap\u00e1 no es as\u00ed. El me ense\u00f1\u00f3 a ser caballeroso<\/span><a id=\"glossary_4\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/como\/#family_4\"><b>[iv]<\/b><\/a><span style=\"font-weight: 400;\"> y a respetar a las mujeres. Mis t\u00edos y primos tambi\u00e9n son muy respetuosos y cari\u00f1osos con mis t\u00edas.<\/span><\/p><p><span style=\"font-weight: 400;\">Yo no estoy de acuerdo con mi pap\u00e1 de que el problema de Jorge sea personal y que no haya nada que hacer, pero no lo quise contradecir enfrente de mi mam\u00e1.<\/span><a id=\"glossary_5\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/como\/#family_5\"><b>[v]<\/b><\/a><span style=\"font-weight: 400;\"> De hecho, mi amigo Jack varias veces me ha invitado a un grupo de hombres que se juntan a conversar y a organizar actividades en contra de la violencia dom\u00e9stica. La verdad es que no he querido ir porque no s\u00e9 si habr\u00e1 otros latinos en el grupo, pero necesito buscar ayuda para Jorge. No voy a abandonar a mi cu\u00f1ada, mis sobrin@s ni a mi hermano.<\/span><\/p><h4><strong>Preguntas de reflexi\u00f3n<\/strong><\/h4><ol><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 tan importante es la familia en la vida de Freddy? \u00bfPor qu\u00e9?<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 opina del hecho que Freddy todav\u00eda vive con sus padres?<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u00bfPor qu\u00e9 cree que Blanca no quiso hablar con Freddy, pero s\u00ed con su suegra?<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 piensa de la actitud del pap\u00e1 de Freddy con respecto a Jorge?<\/span><\/span><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 valores culturales puede identificar en el principio de esta historia? [Sin revisar las notas al final del documento.]<\/span><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86ee2af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86ee2af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9816e83\" data-id=\"9816e83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62132c5 elementor-widget elementor-widget-text-editor\" data-id=\"62132c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>\u00a0<\/div><div style=\"text-align: right;\"><span style=\"font-weight: 200;\">\u00daltima actualizaci\u00f3n 2021<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ejercicio 1: Conocer a Freddy \u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18216,"template":"","meta":{"_cbd_carousel_blocks":"[]"},"media_category":[321,250,255],"media_tags":[290,306,590],"class_list":["post-10621","cde-knowledge-base","type-cde-knowledge-base","status-publish","has-post-thumbnail","hentry","media_category-esperanza-united-departamentos","media_category-kits-de-herramientas","media_category-te-invito-es","media_tags-gratis","media_tags-prevencion","media_tags-recursos-para-jovenes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ejercicio 1: Conocer a Freddy \u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Manish\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ejercicio 1: Conocer a Freddy - Esperanza United\" \/>\n\t\t<meta property=\"og:description\" content=\"Ejercicio 1: Conocer a Freddy \u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-26T09:16:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-27T14:51:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ejercicio 1: Conocer a Freddy - Esperanza United\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ejercicio 1: Conocer a Freddy \u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"name\":\"Knowledge Base\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"position\":2,\"name\":\"Knowledge Base\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"name\":\"Kits de herramientas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"position\":3,\"name\":\"Kits de herramientas\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/te-invito-es\\\/#listItem\",\"name\":\"Te invito\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"name\":\"Knowledge Base\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/te-invito-es\\\/#listItem\",\"position\":4,\"name\":\"Te invito\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/te-invito-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/#listItem\",\"name\":\"Ejercicio 1: Conocer a Freddy\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/kits-de-herramientas\\\/#listItem\",\"name\":\"Kits de herramientas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/#listItem\",\"position\":5,\"name\":\"Ejercicio 1: Conocer a Freddy\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/te-invito-es\\\/#listItem\",\"name\":\"Te invito\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/\",\"name\":\"Manish\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54c203425d096cb9d4ecf6f339772103c5a7fb592c84c1599a524e3921ba945a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Manish\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/#webpage\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/\",\"name\":\"Ejercicio 1: Conocer a Freddy - Esperanza United\",\"description\":\"Ejercicio 1: Conocer a Freddy \\u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\\u00f1os, soy soltero y estoy en el \\u00faltimo a\\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dgdev\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3.png\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/#mainImage\",\"width\":1080,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/te-invito-es\\\/ejercicio-1-conocer-a-freddy\\\/#mainImage\"},\"datePublished\":\"2021-09-26T09:16:57-05:00\",\"dateModified\":\"2025-08-27T09:51:13-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ejercicio 1: Conocer a Freddy - Esperanza United","description":"Ejercicio 1: Conocer a Freddy \u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos","canonical_url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/esperanzaunited.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","name":"Knowledge Base"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","position":2,"name":"Knowledge Base","item":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","name":"Kits de herramientas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","position":3,"name":"Kits de herramientas","item":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/te-invito-es\/#listItem","name":"Te invito"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","name":"Knowledge Base"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/te-invito-es\/#listItem","position":4,"name":"Te invito","item":"https:\/\/esperanzaunited.org\/es\/media_category\/te-invito-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/#listItem","name":"Ejercicio 1: Conocer a Freddy"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/#listItem","name":"Kits de herramientas"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/#listItem","position":5,"name":"Ejercicio 1: Conocer a Freddy","previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/te-invito-es\/#listItem","name":"Te invito"}}]},{"@type":"Organization","@id":"https:\/\/esperanzaunited.org\/es\/#organization","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","url":"https:\/\/esperanzaunited.org\/es\/"},{"@type":"Person","@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author","url":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/","name":"Manish","image":{"@type":"ImageObject","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/54c203425d096cb9d4ecf6f339772103c5a7fb592c84c1599a524e3921ba945a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Manish"}},{"@type":"WebPage","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/#webpage","url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/","name":"Ejercicio 1: Conocer a Freddy - Esperanza United","description":"Ejercicio 1: Conocer a Freddy \u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/#breadcrumblist"},"author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author"},"creator":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dgdev\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3.png","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/#mainImage","width":1080,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/#mainImage"},"datePublished":"2021-09-26T09:16:57-05:00","dateModified":"2025-08-27T09:51:13-05:00"},{"@type":"WebSite","@id":"https:\/\/esperanzaunited.org\/es\/#website","url":"https:\/\/esperanzaunited.org\/es\/","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","inLanguage":"es-ES","publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence","og:type":"article","og:title":"Ejercicio 1: Conocer a Freddy - Esperanza United","og:description":"Ejercicio 1: Conocer a Freddy \u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos","og:url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/","og:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3.png","og:image:secure_url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3.png","og:image:width":1080,"og:image:height":1080,"article:published_time":"2021-09-26T09:16:57+00:00","article:modified_time":"2025-08-27T14:51:13+00:00","twitter:card":"summary","twitter:title":"Ejercicio 1: Conocer a Freddy - Esperanza United","twitter:description":"Ejercicio 1: Conocer a Freddy \u00a1Hola! Me llamo Freddy y vivo con mis padres en el Westside de St. Paul, Minnesota. Tengo 23 a\u00f1os, soy soltero y estoy en el \u00faltimo a\u00f1o de la universidad. Tengo un medio hermano que se llama Jorge y vive con su esposa e hijos en Minneapolis, a 20 minutos","twitter:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/09\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Webinar-3.png"},"aioseo_meta_data":{"post_id":"10621","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-63e6a880c7437","slug":"web-page","graphName":"WebPage","label":"P\u00e1gina web","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-26 09:16:57","updated":"2025-11-22 04:02:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/\" title=\"Knowledge Base\">Knowledge Base<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/\" title=\"Kits de herramientas\">Kits de herramientas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/media_category\/te-invito-es\/\" title=\"Te invito\">Te invito<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEjercicio 1: Conocer a Freddy\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esperanzaunited.org\/es\/"},{"label":"Knowledge Base","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/"},{"label":"Kits de herramientas","link":"https:\/\/esperanzaunited.org\/es\/media_category\/kits-de-herramientas\/"},{"label":"Te invito","link":"https:\/\/esperanzaunited.org\/es\/media_category\/te-invito-es\/"},{"label":"Ejercicio 1: Conocer a Freddy","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/te-invito-es\/ejercicio-1-conocer-a-freddy\/"}],"_links":{"self":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base"}],"about":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/types\/cde-knowledge-base"}],"author":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":20,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10621\/revisions"}],"predecessor-version":[{"id":36902,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/10621\/revisions\/36902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media\/18216"}],"wp:attachment":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media?parent=10621"}],"wp:term":[{"taxonomy":"media_category","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media_category?post=10621"},{"taxonomy":"media_tags","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media_tags?post=10621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}