
{"id":37653,"date":"2025-10-08T11:07:18","date_gmt":"2025-10-08T16:07:18","guid":{"rendered":"https:\/\/esperanzaunited.org\/?post_type=cde-knowledge-base&#038;p=37653"},"modified":"2025-10-08T11:07:18","modified_gmt":"2025-10-08T16:07:18","slug":"boletin-defensa-de-ls-sobrevivientes-inmigrantes-2","status":"publish","type":"cde-knowledge-base","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/","title":{"rendered":"Boletin: Defensa de l@s sobrevivientes inmigrantes"},"content":{"rendered":"<p>Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las mujeres (VAWA, por sus siglas en ingl\u00e9s), esto no es as\u00ed. L@s responsables de pol\u00edticas deben comprender la magnitud de los desaf\u00edos, incluyendo el n\u00famero total acumulado de solicitudes pendientes de visas VAWA, T y U ante el Servicio de ciudadan\u00eda e inmigraci\u00f3n de los Estados Unidos (USCIS, por sus siglas en ingl\u00e9s) que a\u00fan no han sido adjudicadas, as\u00ed como el tiempo que cada caso lleva pendiente.<\/p>\n<h6>Este recurso ha sido posible gracias a 90EV0556 del Departamento de salud y servicios humanos, Administraci\u00f3n para ni\u00f1os y familias. El contenido de este documento es responsabilidad exclusiva de Esperanza United y no refleja necesariamente los puntos de vista oficiales del Departamento de salud y servicios humanos, Administraci\u00f3n para ni\u00f1os y familias.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":37651,"template":"","meta":{"_cbd_carousel_blocks":"[]"},"media_category":[231],"media_tags":[290,280,612],"class_list":["post-37653","cde-knowledge-base","type-cde-knowledge-base","status-publish","has-post-thumbnail","hentry","media_category-pdfs-es","media_tags-gratis","media_tags-politica-publica","media_tags-recursos-para-inmigrantes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"dsullivan@casadeesperanza.org\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Boletin: Defensa de l@s sobrevivientes inmigrantes - Esperanza United\" \/>\n\t\t<meta property=\"og:description\" content=\"Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/05387-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/05387-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-10-08T16:07:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-08T16:07:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Boletin: Defensa de l@s sobrevivientes inmigrantes - Esperanza United\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/05387-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"name\":\"Knowledge Base\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"position\":2,\"name\":\"Knowledge Base\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/tipo-de-contenido\\\/#listItem\",\"name\":\"Tipo de contenido\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/tipo-de-contenido\\\/#listItem\",\"position\":3,\"name\":\"Tipo de contenido\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/tipo-de-contenido\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/pdfs-es\\\/#listItem\",\"name\":\"PDFs\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/%kb-category%\\\/#listItem\",\"name\":\"Knowledge Base\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/pdfs-es\\\/#listItem\",\"position\":4,\"name\":\"PDFs\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/pdfs-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/#listItem\",\"name\":\"Boletin: Defensa de l@s sobrevivientes inmigrantes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/tipo-de-contenido\\\/#listItem\",\"name\":\"Tipo de contenido\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/#listItem\",\"position\":5,\"name\":\"Boletin: Defensa de l@s sobrevivientes inmigrantes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/media_category\\\/pdfs-es\\\/#listItem\",\"name\":\"PDFs\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/\",\"name\":\"dsullivan@casadeesperanza.org\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21c9f1483d8a4dea4829e460b61ff9ace90e41bba353ea78349096b86a29f419?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"dsullivan@casadeesperanza.org\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/#webpage\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/\",\"name\":\"Boletin: Defensa de l@s sobrevivientes inmigrantes - Esperanza United\",\"description\":\"Este documento sirve como una herramienta educativa para responsables de pol\\u00edticas, arrojando luz sobre las brechas existentes en la protecci\\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/05387-scaled.jpg\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/#mainImage\",\"width\":2560,\"height\":1708},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/knowledge-base\\\/pdfs-es\\\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\\\/#mainImage\"},\"datePublished\":\"2025-10-08T11:07:18-05:00\",\"dateModified\":\"2025-10-08T11:07:18-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Boletin: Defensa de l@s sobrevivientes inmigrantes - Esperanza United","description":"Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las","canonical_url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/esperanzaunited.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","name":"Knowledge Base"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","position":2,"name":"Knowledge Base","item":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/tipo-de-contenido\/#listItem","name":"Tipo de contenido"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/tipo-de-contenido\/#listItem","position":3,"name":"Tipo de contenido","item":"https:\/\/esperanzaunited.org\/es\/media_category\/tipo-de-contenido\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/pdfs-es\/#listItem","name":"PDFs"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/#listItem","name":"Knowledge Base"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/pdfs-es\/#listItem","position":4,"name":"PDFs","item":"https:\/\/esperanzaunited.org\/es\/media_category\/pdfs-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/#listItem","name":"Boletin: Defensa de l@s sobrevivientes inmigrantes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/tipo-de-contenido\/#listItem","name":"Tipo de contenido"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/#listItem","position":5,"name":"Boletin: Defensa de l@s sobrevivientes inmigrantes","previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/media_category\/pdfs-es\/#listItem","name":"PDFs"}}]},{"@type":"Organization","@id":"https:\/\/esperanzaunited.org\/es\/#organization","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","url":"https:\/\/esperanzaunited.org\/es\/"},{"@type":"Person","@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author","url":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/","name":"dsullivan@casadeesperanza.org","image":{"@type":"ImageObject","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/21c9f1483d8a4dea4829e460b61ff9ace90e41bba353ea78349096b86a29f419?s=96&d=mm&r=g","width":96,"height":96,"caption":"dsullivan@casadeesperanza.org"}},{"@type":"WebPage","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/#webpage","url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/","name":"Boletin: Defensa de l@s sobrevivientes inmigrantes - Esperanza United","description":"Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/#breadcrumblist"},"author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"creator":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/05387-scaled.jpg","@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/#mainImage","width":2560,"height":1708},"primaryImageOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/#mainImage"},"datePublished":"2025-10-08T11:07:18-05:00","dateModified":"2025-10-08T11:07:18-05:00"},{"@type":"WebSite","@id":"https:\/\/esperanzaunited.org\/es\/#website","url":"https:\/\/esperanzaunited.org\/es\/","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","inLanguage":"es-ES","publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence","og:type":"article","og:title":"Boletin: Defensa de l@s sobrevivientes inmigrantes - Esperanza United","og:description":"Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las","og:url":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/","og:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/05387-scaled.jpg","og:image:secure_url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/05387-scaled.jpg","og:image:width":2560,"og:image:height":1708,"article:published_time":"2025-10-08T16:07:18+00:00","article:modified_time":"2025-10-08T16:07:18+00:00","twitter:card":"summary","twitter:title":"Boletin: Defensa de l@s sobrevivientes inmigrantes - Esperanza United","twitter:description":"Este documento sirve como una herramienta educativa para responsables de pol\u00edticas, arrojando luz sobre las brechas existentes en la protecci\u00f3n de las comunidades inmigrantes y sus impactos adversos en l@s sobrevivientes de violencia de g\u00e9nero. Aunque muchas personas asumen que las soluciones ya han sido abordadas dentro de la Ley sobre la violencia contra las","twitter:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/05387-scaled.jpg"},"aioseo_meta_data":{"post_id":"37653","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-10-08 16:07:03","updated":"2025-11-22 04:16:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/\" title=\"Knowledge Base\">Knowledge Base<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/media_category\/tipo-de-contenido\/\" title=\"Tipo de contenido\">Tipo de contenido<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/media_category\/pdfs-es\/\" title=\"PDFs\">PDFs<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBoletin: Defensa de l@s sobrevivientes inmigrantes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esperanzaunited.org\/es\/"},{"label":"Knowledge Base","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/%kb-category%\/"},{"label":"Tipo de contenido","link":"https:\/\/esperanzaunited.org\/es\/media_category\/tipo-de-contenido\/"},{"label":"PDFs","link":"https:\/\/esperanzaunited.org\/es\/media_category\/pdfs-es\/"},{"label":"Boletin: Defensa de l@s sobrevivientes inmigrantes","link":"https:\/\/esperanzaunited.org\/es\/knowledge-base\/pdfs-es\/boletin-defensa-de-ls-sobrevivientes-inmigrantes-2\/"}],"_links":{"self":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/37653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base"}],"about":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/types\/cde-knowledge-base"}],"author":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":1,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/37653\/revisions"}],"predecessor-version":[{"id":37654,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/cde-knowledge-base\/37653\/revisions\/37654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media\/37651"}],"wp:attachment":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media?parent=37653"}],"wp:term":[{"taxonomy":"media_category","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media_category?post=37653"},{"taxonomy":"media_tags","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media_tags?post=37653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}