
{"id":4994,"date":"2021-08-03T23:24:00","date_gmt":"2021-08-03T23:24:00","guid":{"rendered":"http:\/\/eu.dgweb.co\/?page_id=4994"},"modified":"2025-09-06T14:15:51","modified_gmt":"2025-09-06T19:15:51","slug":"nuestra-gente","status":"publish","type":"page","link":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/nuestra-gente\/","title":{"rendered":"Nuestra gente"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4994\" class=\"elementor elementor-4994 elementor-3090\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-175e868 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"175e868\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e52d91\" data-id=\"3e52d91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-95ac92d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95ac92d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-aac6edc\" data-id=\"aac6edc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e4e44c abuse-sub-title elementor-widget elementor-widget-heading\" data-id=\"5e4e44c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Como organizaci\u00f3n latina, fundamentamos nuestro trabajo en escuchar a nuestras comunidades. Es un honor destacar la belleza, fortalezas y sabidur\u00eda de nuestra gente en este camino para poner fin a la violencia dom\u00e9stica, la agresi\u00f3n sexual, la violencia en el noviazgo y el acecho. Tambi\u00e9n valoramos a nuestr@s aliad@s que nos apoyan en esta labor, y nos enorgullece que nuestro equipo y junta directiva vivan y trabajen en las comunidades a las que servimos.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14a5b0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14a5b0e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fc7d9eb\" data-id=\"fc7d9eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-841706d elementor-widget elementor-widget-text-editor\" data-id=\"841706d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\t<div class=\"row history-row\">\t\t\t\t\n\t\t\t<div class=\"col-md-12 history-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"meet-team-head abuse-title \">\n\t\t\t\t\t\n\t\t\t\t  <h2>\n\t\t\t\t\t   Liderato\t\t\t\t  <\/h2>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"row\" style=\"justify-content: center;\">\t\n\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_21972\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"695\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-768x695.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-768x695.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-300x271.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-1024x926.jpg 1024w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-1536x1389.jpg 1536w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-2048x1853.jpg 2048w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-600x543.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Vivian Huelgo, J.D.<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Presidenta y CEO<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_21972\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"695\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-768x695.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-768x695.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-300x271.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-1024x926.jpg 1024w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-1536x1389.jpg 1536w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-2048x1853.jpg 2048w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/VHuelgo-Pur_199x180_webiste-600x543.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Vivian Huelgo, J.D.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Presidenta y CEO<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span lang=\"es\" data-olk-copy-source=\"MessageBody\">Vivian Huelgo, J.D. es la presidenta y directora ejecutiva de Esperanza United. En su rol, Vivian articula e implementa la visi\u00f3n estrat\u00e9gica de la organizaci\u00f3n y fomenta una cultura de alto rendimiento con un equipo ubicado en las ciudades gemelas, Washington, DC, y diversas partes del pa\u00eds. Fundada hace m\u00e1s de cuarenta a\u00f1os, Esperanza United es la organizaci\u00f3n m\u00e1s grande en los Estados Unidos continentales y territorios, fundada y dirigida por latinas, que moviliza a las comunidades latinas para erradicar la violencia dom\u00e9stica, agresi\u00f3n sexual, violencia en el noviazgo y acecho.<\/span><\/p>\n<p><span lang=\"es\">Vivian ha trabajado en la intersecci\u00f3n entre el derecho y la violencia dom\u00e9stica y sexual por m\u00e1s de veinticinco a\u00f1os. En 2022, se uni\u00f3 a Esperanza United como directora de programas. Durante la d\u00e9cada previa, dirigi\u00f3 la Comisi\u00f3n sobre violencia dom\u00e9stica y sexual de la Asociaci\u00f3n de abogados de Estados Unidos (ABA, por sus siglas en ingl\u00e9s) como asesora principal, enfoc\u00e1ndose intensamente en iniciativas de derechos humanos, violencia dom\u00e9stica y sexual y trata de personas. En la ABA, Vivian desarroll\u00f3 y estableci\u00f3 una visi\u00f3n amplia e inclusiva para el trabajo de la comisi\u00f3n, promovi\u00f3 pol\u00edticas cr\u00edticas, aument\u00f3 su presencia en l\u00ednea y duplic\u00f3 los fondos para entrenamientos y asistencia t\u00e9cnica dirigidos a abogad@s a nivel nacional.<\/span><\/p>\n<p><span lang=\"es\">En 2015, Vivian fue seleccionada como becaria del programa Move to End Violence, de la fundaci\u00f3n NoVo. Tambi\u00e9n recibi\u00f3 el premio Flor de Maga para mujeres en la profesi\u00f3n legal de la Asociaci\u00f3n de abogad@s puertorrique\u00f1@s. Es graduada de la facultad de derecho de la Universidad de Fordham, donde fue profesora asociada adjunta de derecho y recibi\u00f3 tanto el Andrew A. Rivera Alumni Achievement Award como el Louis J. Lefkowitz Public Service Award.\u00a0<\/span><\/p>\n<p><span lang=\"es\">Nacida en Brooklyn y criada en la ciudad de Nueva York, Vivian es madre de gemelos y vive en el \u00e1rea metropolitana de Washington, DC.<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_22328\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"695\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-768x695.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"Adriana Alejandro\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-768x695.png 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-300x271.png 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-1024x926.png 1024w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-600x543.png 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized.png 1130w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Adriana Alejandro Osorio, Ph.D.<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Oficial de avance<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_22328\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"695\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-768x695.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"Adriana Alejandro\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-768x695.png 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-300x271.png 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-1024x926.png 1024w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized-600x543.png 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2024\/06\/Adriana-2024-Headshot-sized.png 1130w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Adriana Alejandro Osorio, Ph.D.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Oficial de avance<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p>La Dra. Adriana Alejandro Osorio es una l\u00edder en el avance de la justicia social, y se mantiene firmemente al lado de las latinas y las comunidades latinas tanto en los Estados Unidos como internacionalmente. A lo largo de su carrera en los sectores sin fines de lucro y de filantrop\u00eda, ha defendido iniciativas que promueven la salud y el desarrollo global, avanzan hacia los objetivos de desarrollo sostenible de las Naciones Unidas, y amplifican los derechos y la participaci\u00f3n de l@s ni\u00f1@s en los EE.UU. y en el mundo.<\/p>\n<p>En su rol en Esperanza United, Adriana lidera nuestros esfuerzos de avance y desarrollo, para co-crear y catalizar nuestra trabajo de movilizar a las latinas y las comunidades latinas para poner un fin a la violencia dom\u00e9stica, agresi\u00f3n sexual, violencia en el noviazgo y acecho. Ella es instrumental en el desarrollo de asociaciones estrat\u00e9gicas y oportunidades, impulsando la estrategia integral de la movilizaci\u00f3n de recursos y fondos de la organizaci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_39799\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-1024x1024.jpg 1024w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Mario Franco<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Director de operaciones y finanzas<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_39799\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-1024x1024.jpg 1024w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Untitled-design-15.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Mario Franco<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Director de operaciones y finanzas<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"p1\">Mario Franco es un\u00a0ejecutivo\u00a0de alto\u00a0nivel\u00a0(C-suite) y\u00a0agente\u00a0de\u00a0transformaci\u00f3n\u00a0con\u00a0m\u00e1s\u00a0de 20\u00a0a\u00f1os\u00a0de\u00a0experiencia\u00a0liderando\u00a0organizaciones\u00a0complejas\u00a0y\u00a0multisectoriales\u00a0a\u00a0trav\u00e9s\u00a0de\u00a0procesos\u00a0de\u00a0crecimiento\u00a0operativo,\u00a0optimizaci\u00f3n\u00a0financiera\u00a0y\u00a0cambio\u00a0a\u00a0nivel\u00a0institucional. Es\u00a0reconocido\u00a0por\u00a0fortalecer\u00a0el\u00a0desempe\u00f1o\u00a0organizacional,\u00a0escalar\u00a0sistemas\u00a0y\u00a0construir\u00a0equipos\u00a0de alto\u00a0impacto\u00a0que\u00a0generan\u00a0resultados\u00a0medibles\u00a0y\u00a0alineados\u00a0con la\u00a0misi\u00f3n.<\/p>\n<p class=\"p1\">La\u00a0trayectoria\u00a0de Franco\u00a0abarca\u00a0los\u00a0sectores\u00a0sin fines de\u00a0lucro,\u00a0salud,\u00a0gobierno,\u00a0militar\u00a0y\u00a0corporativo,\u00a0donde\u00a0se ha\u00a0desempe\u00f1ado\u00a0como\u00a0director de\u00a0operaciones, director\u00a0financiero, director de\u00a0programas,\u00a0contralor\u00a0y\u00a0asesor\u00a0s\u00e9nior\u00a0en\u00a0distintos\u00a0contextos\u00a0operativos. Su\u00a0portafolio\u00a0de\u00a0liderazgo\u00a0incluye\u00a0operaciones\u00a0empresariales,\u00a0gesti\u00f3n\u00a0financiera,\u00a0supervisi\u00f3n\u00a0de\u00a0programas,\u00a0adquisiciones\u00a0y\u00a0contrataci\u00f3n,\u00a0preparaci\u00f3n\u00a0para\u00a0fusiones\u00a0y\u00a0adquisiciones,\u00a0desarrollo\u00a0organizacional\u00a0e\u00a0iniciativas\u00a0de\u00a0transformaci\u00f3n\u00a0a gran\u00a0escala.<\/p>\n<p class=\"p1\">Ha\u00a0dirigido\u00a0programas\u00a0e\u00a0iniciativas\u00a0con un\u00a0impacto\u00a0econ\u00f3mico,\u00a0operativo\u00a0y\u00a0educativo\u00a0superior a\u00a0los\u00a0100 mil\u00a0millones\u00a0de\u00a0d\u00f3lares, tanto a\u00a0nivel\u00a0nacional\u00a0como\u00a0internacional. Su\u00a0trabajo\u00a0incluye\u00a0la\u00a0gesti\u00f3n\u00a0de\u00a0presupuestos\u00a0multimillonarios, la\u00a0supervisi\u00f3n\u00a0de\u00a0sistemas\u00a0operativos\u00a0complejos\u00a0en\u00a0servicios\u00a0sociales\u00a0y\u00a0salud, el\u00a0impulso\u00a0de la\u00a0innovaci\u00f3n\u00a0institucional\u00a0y el\u00a0acompa\u00f1amiento\u00a0de\u00a0organizaciones\u00a0en\u00a0procesos\u00a0de\u00a0reestructuraci\u00f3n,\u00a0crecimiento\u00a0y\u00a0modernizaci\u00f3n.<\/p>\n<p class=\"p1\">Como\u00a0conferencista\u00a0experimentado\u00a0y\u00a0referente\u00a0en\u00a0su\u00a0campo, Franco ha\u00a0presentado\u00a0en\u00a0Estados\u00a0Unidos y\u00a0en\u00a0el\u00a0extranjero\u00a0sobre\u00a0planificaci\u00f3n\u00a0estrat\u00e9gica,\u00a0excelencia\u00a0operativa,\u00a0responsabilidad\u00a0fiscal,\u00a0desarrollo\u00a0de\u00a0liderazgo,\u00a0participaci\u00f3n\u00a0del personal y\u00a0colaboraci\u00f3n\u00a0intersectorial. Tambi\u00e9n\u00a0sirvi\u00f3\u00a020\u00a0a\u00f1os\u00a0en\u00a0el Cuerpo de Marines de\u00a0Estados\u00a0Unidos,\u00a0donde\u00a0ocup\u00f3\u00a0roles\u00a0como\u00a0comandante y\u00a0oficial\u00a0ejecutivo,\u00a0oficial\u00a0de\u00a0finanzas,\u00a0administrador\u00a0legal y\u00a0gerente\u00a0de\u00a0programas.<\/p>\n<p class=\"p1\">Franco es\u00a0egresado\u00a0de Stanford Graduate School of Business (innovaci\u00f3n\u00a0corporativa) y de Harvard Business School (liderazgo\u00a0desde\u00a0las\u00a0finanzas), y\u00a0cuenta\u00a0con\u00a0certificaciones\u00a0avanzadas\u00a0en\u00a0gesti\u00f3n\u00a0de\u00a0proyectos,\u00a0contrataci\u00f3n,\u00a0contabilidad,\u00a0inteligencia\u00a0artificial\u00a0generativa\u00a0para\u00a0l\u00edderes\u00a0empresariales\u00a0y\u00a0gesti\u00f3n\u00a0financiera. Es\u00a0miembro\u00a0activo\u00a0de\u00a0asociaciones\u00a0profesionales\u00a0destacadas, entre\u00a0ellas\u00a0el Institute of Management Accountants, SHRM, ASMC, ACHE, HFMA, y\u00a0organizaciones\u00a0de\u00a0servicio\u00a0a\u00a0veteranos.<\/p>\n<p class=\"p1\">Se le\u00a0reconoce\u00a0por\u00a0su\u00a0capacidad\u00a0para\u00a0alinear\u00a0la\u00a0estrategia\u00a0con la\u00a0ejecuci\u00f3n,\u00a0fomentar\u00a0culturas\u00a0colaborativas\u00a0e\u00a0inclusivas, y\u00a0guiar\u00a0a las\u00a0organizaciones\u00a0hacia\u00a0la\u00a0sostenibilidad\u00a0a largo\u00a0plazo, la\u00a0excelencia\u00a0operativa\u00a0y el\u00a0impacto\u00a0en\u00a0su\u00a0misi\u00f3n.<\/p>\n<p class=\"p1\">Dale la\u00a0bienvenida\u00a0a Mario al\u00a0equipo\u00a0de Esperanza United.<\/p>\n<p class=\"p1\">\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_6625\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"398\" height=\"360\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/AnnikaWebsitePhoto-1-1.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/AnnikaWebsitePhoto-1-1.png 398w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/AnnikaWebsitePhoto-1-1-300x271.png 300w\" sizes=\"(max-width: 398px) 100vw, 398px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Annika Gifford<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Oficial de estrategia e impacto<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_6625\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"398\" height=\"360\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/AnnikaWebsitePhoto-1-1.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/AnnikaWebsitePhoto-1-1.png 398w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/AnnikaWebsitePhoto-1-1-300x271.png 300w\" sizes=\"(max-width: 398px) 100vw, 398px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Annika Gifford<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Oficial de estrategia e impacto<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Annika Gifford ha trabajado en la intersecci\u00f3n de la justicia social y los derechos humanos tanto internacionalmente como en Estados Unidos durante 25 a\u00f1os. Como Oficial de estrategia e impacto en Esperanza United, pone en pr\u00e1ctica la misi\u00f3n de la organizaci\u00f3n con una visi\u00f3n estrat\u00e9gica, fomenta una cultura de excelencia basada en valores y promueve enfoques centrados en fortalezas para poner fin a la violencia de g\u00e9nero.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Antes de unirse a Esperanza United, Annika ayud\u00f3 a facilitar el lanzamiento de Resonance Network, una red de personas que creen que un mundo sin violencia es posible. Tambi\u00e9n ha ocupado puestos de alto nivel en pol\u00edticas p\u00fablicas, investigaci\u00f3n y programas con Break the Cycle y el National Resource Center on Domestic Violence, adem\u00e1s de trabajar en el Centre for Women\u2019s Studies en Zagreb, Croacia, en el periodo posterior al conflicto. Mientras viv\u00eda en Croacia, cofund\u00f3 una organizaci\u00f3n no gubernamental croata que promueve una mayor inclusi\u00f3n social de ni\u00f1@s y j\u00f3venes con discapacidades.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Annika tiene una Maestr\u00eda en Artes en Gender and Peacebuilding de la University for Peace, que tiene un mandato de las Naciones Unidas, en Costa Rica. Form\u00f3 parte de la Segunda Cohorte del programa Move to End Violence de la NoVo Foundation. Es miembro fundadora del consejo directivo del Asian Pacific Institute on Gender-Based Violence y form\u00f3 parte de la junta del Battered Women\u2019s Justice Project. Annika tambi\u00e9n es miembro de la familia donante de Building More Philanthropy with Purpose, o Bad Mo Pho Phamily, integrada por familias panasi\u00e1ticas que creen que un mejor futuro es posible para tod@s cuando nos unimos para celebrar, aprender y brindar recursos que impulsen el cambio que deseamos ver en el mundo.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37019\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Jeanette Bowden<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Gerente principal de participaci\u00f3n sist\u00e9mica e incidencia<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37019\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Jeanette Bowden<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Gerente principal de participaci\u00f3n sist\u00e9mica e incidencia<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Jeanette (Soto) Bowden cuenta con m\u00e1s de dos d\u00e9cadas de experiencia trabajando en el campo de la violencia de g\u00e9nero. Actualmente se desempe\u00f1a como Gerente principal de participaci\u00f3n sist\u00e9mica e incidencia en Esperanza United. En ese rol, lidera tres proyectos financiados por la Office of Violence Against Women, cada uno enfocado en intervenciones sist\u00e9micas para reducir los homicidios por violencia dom\u00e9stica.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Su experiencia multifac\u00e9tica supervisando programaci\u00f3n residencial, comunitaria y culturalmente espec\u00edfica en Nueva York, Michigan y Georgia contribuye a su \u00e9xito y liderazgo en la gesti\u00f3n de proyectos, supervisi\u00f3n presupuestaria, supervisi\u00f3n culturalmente pertinente e informada sobre el trauma, y relaciones comunitarias. Como facilitador@ y capacitador@ con experiencia, ha fortalecido la capacidad de organizaciones y personas que responden a sobrevivientes racial y \u00e9tnicamente divers@s de violencia de g\u00e9nero.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Adem\u00e1s, Jeanette tiene experiencia en revisiones de casos fatales, respuestas comunitarias coordinadas y evaluaciones de letalidad, brindando capacitaci\u00f3n a agencias policiales, personal m\u00e9dico y organizaciones comunitarias. A lo largo de su carrera, ha elevado de forma constante las necesidades de l@s sobrevivientes latin@s y ha incrementado su acceso a servicios para prevenir homicidios por parte de parejas \u00edntimas.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Primera en su familia en graduarse de la universidad, Jeanette naci\u00f3 y se cri\u00f3 en la ciudad de Nueva York, hija de padres puertorrique\u00f1os nacidos en la isla.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37083\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Nallely Castro Montoya<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Subdirectora de prevenci\u00f3n y cambio social<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37083\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/17.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Nallely Castro Montoya<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Subdirectora de prevenci\u00f3n y cambio social<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Nallely Castro Montoya se desempe\u00f1a como Subdirectora de prevenci\u00f3n y cambio social en Esperanza United. Nallely est\u00e1 comprometida con el avance de enfoques culturalmente pertinentes y centrados en la comunidad para la prevenci\u00f3n de la violencia de g\u00e9nero y el empoderamiento juvenil. En su rol en Esperanza United, supervisa las iniciativas de prevenci\u00f3n de la organizaci\u00f3n en las Twin Cities, gestiona subvenciones y presupuestos, y asegura la alineaci\u00f3n con los objetivos y expectativas organizacionales. Nallely tambi\u00e9n lidera el desarrollo de programas, la evaluaci\u00f3n y el fortalecimiento de capacidades.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Antes de su trabajo en Esperanza United, Nallely se desempe\u00f1\u00f3 como Mental Health Practitioner en Family Innovations, brindando apoyo terap\u00e9utico individualizado y centrado en la familia a ni\u00f1@s de edad escolar primaria. Nallely tambi\u00e9n trabaj\u00f3 como School Social Work Intern en Adolescent Girls and Parenting Education (AGAPE) High School. All\u00ed cofacilit\u00f3 grupos de apoyo enfocados en relaciones interpersonales y empoderamiento personal, apoyando a l@s estudiantes en el desarrollo de estrategias de afrontamiento para situaciones dif\u00edciles.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Actualmente forma parte del Latino Consent Decree Parent Advisory Council de Saint Paul Public Schools, que apoya a l@s estudiantes latin@s en el desarrollo de habilidades acad\u00e9micas y personales esenciales para cumplir con los est\u00e1ndares de rendimiento del distrito.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Nallely posee un Bachillerato en Artes en estudios chicano-latinos, un Bachillerato en Ciencia en ciencias sociales de familia y un MSW de la Universidad de Minnesota\u2013Twin Cities.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37111\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Alexander Delgado<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Director de pol\u00edtica<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37111\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/Board-headshots-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Alexander Delgado<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Director de pol\u00edtica<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Alexander Delgado es un intercesor comprometido con las comunidades marginadas, y ha enfocado su carrera en promover pol\u00edticas y sistemas en todos los niveles de gobierno para poner fin a la trata de personas y la violencia de g\u00e9nero. Con un enfoque estrat\u00e9gico, centrado en l@s sobrevivientes y compasivo, Alexander ha sobresalido en la reforma de pol\u00edticas, intercesor\u00eda legislativa y construcci\u00f3n de coaliciones, trabajando en \u00e1reas clave como la lucha contra la trata, la seguridad y privacidad en l\u00ednea, y otras iniciativas relacionadas con la violencia de g\u00e9nero.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Actualmente, como <\/span><span data-contrast=\"auto\">Director de pol\u00edtica en Esperanza <\/span><span data-contrast=\"auto\">United, contin\u00faa impulsando cambios significativos, abogando por temas cr\u00edticos que afectan a las comunidades latinas y m\u00e1s all\u00e1.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Antes de su cargo actual, Alexander se desempe\u00f1\u00f3 como Director of Policy en Protect All Children from Trafficking (PACT), donde lider\u00f3 esfuerzos para promover legislaci\u00f3n contra la trata en el Congreso. Su experiencia previa incluye roles como Program Officer en el U.S. Committee for Refugees and Immigrants, donde mejor\u00f3 los servicios para sobrevivientes LGBTQ+ y sobrevivientes extranjer@s de explotaci\u00f3n, y como Senior Case Manager en Sanctuary for Families, brindando apoyo directo a sobrevivientes en su interacci\u00f3n con los sistemas de asistencia social e inmigraci\u00f3n.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Nacido en Lima, Per\u00fa y criado en Nueva Jersey, Alexander tiene un Bachillerato en Ciencia (Neurobiolog\u00eda) de Boston University y una Maestr\u00eda en Policy Management de Georgetown University.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37031\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Patricia Emmanuelli<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Gerente principal de salud comunitaria y prevenci\u00f3n de la violencia<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37031\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/15.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Patricia Emmanuelli<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Gerente principal de salud comunitaria y prevenci\u00f3n de la violencia<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Patricia Emmanuelli se desempe\u00f1a como Gerente principal de salud comunitaria y prevenci\u00f3n de la violencia en Esperanza United. Brinda gesti\u00f3n de proyectos, supervisi\u00f3n de presupuestos y una supervisi\u00f3n informada sobre el trauma y culturalmente pertinente, mientras gestiona alianzas comunitarias y nacionales.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Los a\u00f1os de experiencia de Patricia apoyando a sobrevivientes de agresi\u00f3n sexual en Florida y Puerto Rico, y su uso de datos y evaluaci\u00f3n, han contribuido a su \u00e9xito en la creaci\u00f3n y mejora de programaci\u00f3n culturalmente pertinente.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Patricia contribuye a m\u00faltiples iniciativas nacionales como Seek and Speak de End Violence Against Women International, un sitio web que apoya a sobrevivientes de agresi\u00f3n sexual en la recopilaci\u00f3n de informaci\u00f3n y en la denuncia ante las autoridades; el Sexual Assault Medical Forensic Exam Virtual Practicum, una plataforma de aprendizaje en l\u00ednea que capacita a profesionales m\u00e9dicos para recolectar evidencia en ex\u00e1menes forenses por agresi\u00f3n sexual; y el Economic Opportunity Project de Future Without Violence, un consorcio de aliad@s nacionales que trabajan para aumentar las protecciones laborales para l@s sobrevivientes.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">P<\/span><span data-contrast=\"auto\">atricia contin\u00faa trabajando con sobrevivientes de agresi\u00f3n sexual brindando apoyo e intercesor\u00eda en su centro local de crisis por violaci\u00f3n, y actualmente est\u00e1 cursando una maestr\u00eda en salud p\u00fablica en la University of Florida.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37075\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Dani Garcia<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Directora de recursos humanos<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37075\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/18.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Dani Garcia<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Directora de recursos humanos<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Dani Garcia, Directora de recursos humanos en Esperanza United, cuenta con m\u00e1s de 14 a\u00f1os de experiencia en recursos humanos, incluyendo adquisici\u00f3n de talento, beneficios, entrevistas de salida, retenci\u00f3n de emplead@s, capacitaci\u00f3n, mentor\u00eda y desarrollo, as\u00ed como gesti\u00f3n del desempe\u00f1o, con una especializaci\u00f3n en relaciones laborales. Ha trabajado en diversas industrias y equipos, lo cual le ha brindado una experiencia amplia e inclusiva, conocimientos y perspectivas \u00fatiles sobre la cultura organizacional, procesos, pol\u00edticas, gesti\u00f3n del cambio y todo el ciclo de vida de l@s emplead@s.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Dani tiene v\u00ednculos geogr\u00e1ficos y culturales con Esperanza United. Naci\u00f3 y creci\u00f3 en el lado este de St. Paul y disfrut\u00f3 crecer en esta vibrante y diversa comunidad, la cual sigue siendo su hogar.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37077\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Paula Gomez Stordy, M.Ed.<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Directora principal nacional de capacitaci\u00f3n y asistencia t\u00e9cnica<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37077\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/14.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Paula Gomez Stordy, M.Ed.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Directora principal nacional de capacitaci\u00f3n y asistencia t\u00e9cnica<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Paula Gomez Stordy tiene m\u00e1s de 30 a\u00f1os de experiencia trabajando en el campo de la prevenci\u00f3n de la violencia dom\u00e9stica y la agresi\u00f3n sexual, de los cuales 20 han sido en la gesti\u00f3n de organizaciones sin fines de lucro. Como <\/span><span data-contrast=\"auto\">Directora principal nacional de capacitaci\u00f3n y asistencia t\u00e9cnica <\/span><span data-contrast=\"auto\">en Esperanza United, dirige las actividades de capacitaci\u00f3n y asistencia t\u00e9cnica, supervisando subvenciones federales, presupuestos de programaci\u00f3n y personal, quienes ofrecen capacitaci\u00f3n y asistencia t\u00e9cnica de vanguardia en todo el pa\u00eds y Puerto Rico.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Como experta en la materia, Paula ha liderado cientos de conferencias magistrales, presentaciones y talleres a nivel nacional y en el Caribe y Am\u00e9rica Latina. Ha asesorado a organizaciones sin fines de lucro en \u00e1reas como recaudaci\u00f3n de fondos, desarrollo de juntas directivas, desarrollo organizacional, desarrollo de liderazgo y programaci\u00f3n estrat\u00e9gica.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A lo largo de su carrera, ha desempe\u00f1ado roles clave en diversos entornos como hospitales, tribunales, refugios y organizaciones comunitarias. Adem\u00e1s, trabaj\u00f3 como profesora adjunta en Merrimack College.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37079\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Lillie Macias, Ph.D.<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Directora de investigaci\u00f3n y evaluaci\u00f3n<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37079\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/19.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Lillie Macias, Ph.D.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Directora de investigaci\u00f3n y evaluaci\u00f3n<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Lillie Macias, Ph.D., dirige el Centro de investigaci\u00f3n y evaluaci\u00f3n de Esperanza United mediante una alianza universidad-comunidad con la University of New Haven, donde es Profesora asociada en psicolog\u00eda.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Complet\u00f3 sus estudios doctorales en Clinical-Community Psychology en Georgia State University y obtuvo una beca cl\u00ednica-comunitaria y un posdoctorado en Yale School of Medicine. Lillie se especializa en investigaci\u00f3n y prevenci\u00f3n comunitaria del trauma, y en la mentor\u00eda de estudiantes y j\u00f3venes profesionales desde secundaria hasta nivel de posgrado en m\u00e9todos de investigaci\u00f3n participativa, evaluaci\u00f3n de programas y desarrollo de programas.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Es orgullosa nieta de trabajadores agr\u00edcolas de California y disfruta pasar su tiempo libre con su familia en Connecticut.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37081\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Sarahi Mateo<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Subdirectora de servicios de intercesor\u00eda familiar<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37081\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/13.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Sarahi Mateo<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Subdirectora de servicios de intercesor\u00eda familiar<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Sarahi Mateo se desempe\u00f1a actualmente como Subdirectora de servicios de intercesor\u00eda familiar en Esperanza United. En este cargo, se ha consolidado como una l\u00edder de confianza dentro de la organizaci\u00f3n y en toda la red de defensa contra la violencia dom\u00e9stica del estado de Minnesota, gracias a su liderazgo con los pies en la tierra, su profundo entendimiento de la comunidad latina y su compromiso con pr\u00e1cticas centradas en l@s sobrevivientes, incluyendo el enfoque basado en fortalezas de Esperanza United.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Sarahi supervisa estrat\u00e9gicamente la programaci\u00f3n del Apoyo a las familias de Esperanza United, que incluye nuestro Refugio, servicios comunitarios\/m\u00f3viles y la \u00fanica l\u00ednea de crisis 24\/7 en Minnesota en espa\u00f1ol e ingl\u00e9s. Lidera un equipo multidisciplinario, asegurando que brindemos constantemente servicios culturalmente pertinentes, informados sobre el trauma e integrales a l@s sobrevivientes de violencia dom\u00e9stica, agresi\u00f3n sexual y acoso.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Durante su tiempo en Esperanza United, Sarahi ha liderado iniciativas que fortalecen alianzas comunitarias, ampl\u00edan el acceso a recursos esenciales para l@s sobrevivientes y promueven la seguridad y estabilidad a largo plazo para l@s participantes del programa. Con m\u00e1s de diez a\u00f1os de experiencia en el campo de la violencia dom\u00e9stica, su experiencia abarca la intervenci\u00f3n en crisis, el desarrollo del personal, la gesti\u00f3n de subvenciones y la defensa sist\u00e9mica, todo basado en un profundo compromiso con la sanaci\u00f3n comunitaria y una pasi\u00f3n por elevar y empoderar a l@s sobrevivientes y sus familias para vivir libres de violencia.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_37085\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Nancy Nava, MPH<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Gerente principal de investigaci\u00f3n y evaluaci\u00f3n<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_37085\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/09\/16.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Nancy Nava, MPH<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Gerente principal de investigaci\u00f3n y evaluaci\u00f3n<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Nancy Nava es Gerente principal de investigaci\u00f3n y evaluaci\u00f3n en Esperanza United. Nancy recibi\u00f3 su Maestr\u00eda en salud p\u00fablica de Georgia State University y ha enfocado su formaci\u00f3n y trabajo en los impactos de los determinantes sociales en las comunidades latinas.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">En Esperanza United, dise\u00f1a, implementa y eval\u00faa programas. Tambi\u00e9n brinda capacitaci\u00f3n y asistencia t\u00e9cnica sobre pr\u00e1cticas de investigaci\u00f3n y evaluaci\u00f3n a organizaciones comunitarias latinas. Los intereses de investigaci\u00f3n de Nancy incluyen la evaluaci\u00f3n de programas, la investigaci\u00f3n acci\u00f3n participativa, las mejores pr\u00e1cticas para la inclusi\u00f3n de j\u00f3venes con discapacidades en todos los entornos y la difusi\u00f3n de pr\u00e1cticas basadas en evidencia centradas en la comunidad.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t       \n\t\t\t\t\t<\/div>  \n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>  \n\t\t<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-384e57f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"384e57f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2f195f6\" data-id=\"2f195f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-176a3ed elementor-widget elementor-widget-shortcode\" data-id=\"176a3ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t<div class=\"row history-row\">\t\t\t\t\n\t\t\t<div class=\"col-md-12 history-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"meet-team-head abuse-title \">\n\t\t\t\t\t\n\t\t\t\t  <h2>\n\t\t\t\t\t   Junta Directiva\t\t\t\t  <\/h2>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"row\" style=\"justify-content: center;\">\t\n\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_22337\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Gloria Contreras Edin, J.D.<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Presidenta | Owner, Managing Attorney, Contreras Edin Law, PA<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_22337\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Gloria Contreras Edin, J.D.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Presidenta | Owner, Managing Attorney, Contreras Edin Law, PA<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"none\">Gloria Contreras Edin, J.D.<\/span><\/b><span data-contrast=\"none\">\u00a0es una abogada c\u00e1lida y compasiva, comprometida con sus clientes y con la defensa de sus derechos seg\u00fan la Constituci\u00f3n de los Estados Unidos. Cuenta con amplia experiencia asesorando a personas de todo el mundo en asuntos migratorios complejos, represent\u00e1ndolas ante diversas cortes y agencias.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Gloria tambi\u00e9n es una defensora apasionada, y forma parte de varias juntas directivas y comisiones de organizaciones sin fines de lucro. Adem\u00e1s, es profesora adjunta de Derecho Migratorio en la Facultad de Derecho Mitchell Hamline.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_35653\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Mar\u00eda C. Pab\u00f3n Gautier, Ph.D.<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Vicepresidenta | Chief People Officer, Project for Pride in Living<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_35653\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Mar\u00eda C. Pab\u00f3n Gautier, Ph.D.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Vicepresidenta | Chief People Officer, Project for Pride in Living<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"none\">La Dra. Mar\u00eda C. Pab\u00f3n Gautier<\/span><\/b><span data-contrast=\"none\"> es Directora de Personas (<\/span><i><span data-contrast=\"none\">Chief People Officer<\/span><\/i><span data-contrast=\"none\">) en <\/span><i><span data-contrast=\"none\">Project for Pride in Living<\/span><\/i><span data-contrast=\"none\">, con sede en Minneapolis, MN. En este cargo, lidera las estrategias y programas de equidad racial, recursos humanos, desarrollo de talento, administraci\u00f3n\/operaciones y la divisi\u00f3n de preparaci\u00f3n profesional. Mar\u00eda tiene un doctorado en Psicolog\u00eda Educativa de la Universidad de Minnesota y una licenciatura en Psicolog\u00eda de la Universidad de Puerto Rico. Con m\u00e1s de 20 a\u00f1os de experiencia, ha dedicado su carrera a la formaci\u00f3n, el acompa\u00f1amiento, la docencia y la investigaci\u00f3n para desarrollar pr\u00e1cticas fundamentadas en evidencia.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Su amplia trayectoria abarca organizaciones sin fines de lucro, instituciones de educaci\u00f3n superior, el sector privado, educaci\u00f3n K-12 y agencias gubernamentales, siempre con un enfoque en el apoyo a comunidades desatendidas y marginadas. Su trabajo se basa en un enfoque interdisciplinario y diverso, con un compromiso firme hacia la justicia, equidad, diversidad e inclusi\u00f3n (JEDI, por sus siglas en ingl\u00e9s) en diversos entornos.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Antes de su puesto actual, Mar\u00eda fue Vicepresidenta de Equidad e Inclusi\u00f3n en <\/span><i><span data-contrast=\"none\">St. Olaf College<\/span><\/i><span data-contrast=\"none\">. A lo largo de su carrera, ha sido guiada por principios de compromiso comunitario, la filosof\u00eda de <\/span><i><span data-contrast=\"none\">\u201cpor nosotrxs, para nosotrxs\u201d<\/span><\/i><span data-contrast=\"none\"> y una base s\u00f3lida en investigaci\u00f3n, medici\u00f3n y evaluaci\u00f3n.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Su enfoque se centra especialmente en la equidad racial y metodolog\u00edas basadas en fortalezas, asegurando que las comunidades de color est\u00e9n al centro del desarrollo y de los procesos de toma de decisiones. Su labor busca fomentar entornos inclusivos donde todas las personas puedan prosperar y contribuir de manera significativa.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_22330\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Gloria Perez<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Secretaria | President & CEO, Women\u2019s Foundation of MN<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_22330\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/6.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Gloria Perez<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Secretaria | President & CEO, Women\u2019s Foundation of MN<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"none\">Gloria Perez<\/span><\/b><span data-contrast=\"none\"> es presidenta y directora ejecutiva de la <\/span><i><span data-contrast=\"none\">Women\u2019s Foundation of Minnesota<\/span><\/i><span data-contrast=\"none\"> (WFM), la primera fundaci\u00f3n estatal en los Estados Unidos dedicada a las mujeres. Desde 1983, WFM realiza investigaciones continuas sobre la situaci\u00f3n de las mujeres y ni\u00f1as en Minnesota, promueve pol\u00edticas p\u00fablicas que fortalecen la seguridad econ\u00f3mica y la protecci\u00f3n de las mujeres y sus familias, e invierte en organizaciones y l\u00edderes para fortalecer el campo y avanzar hacia la justicia de g\u00e9nero y racial \u2014 incluyendo la distribuci\u00f3n de m\u00e1s de 54 millones de d\u00f3lares en inversiones comunitarias.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Gloria se convirti\u00f3 en una de las principales expertas del pa\u00eds en la reducci\u00f3n de la pobreza como presidenta y directora ejecutiva de <\/span><i><span data-contrast=\"none\">Jeremiah Program<\/span><\/i><span data-contrast=\"none\">, una organizaci\u00f3n nacional sin fines de lucro cuyo enfoque hol\u00edstico y comprobado transforma la seguridad econ\u00f3mica de las familias, impactando a dos generaciones al mismo tiempo. Cuenta con m\u00e1s de 25 a\u00f1os de experiencia en distintos sectores, que abarcan desde peque\u00f1as empresas y corporaciones con fines de lucro hasta organizaciones sin fines de lucro de servicios humanos.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Como becaria <\/span><i><span data-contrast=\"none\">Ascend<\/span><\/i><span data-contrast=\"none\"> del Instituto Aspen, Gloria trabaja junto a l\u00edderes nacionales para impulsar ideas innovadoras y estrategias comprobadas que ayuden a las familias a lograr \u00e9xito educativo y seguridad econ\u00f3mica. Forma parte de las juntas directivas de <\/span><i><span data-contrast=\"none\">Ciresi Walburn Foundation<\/span><\/i><span data-contrast=\"none\">, <\/span><i><span data-contrast=\"none\">Esperanza United<\/span><\/i><span data-contrast=\"none\">, <\/span><i><span data-contrast=\"none\">Macalester College<\/span><\/i><span data-contrast=\"none\"> y la <\/span><i><span data-contrast=\"none\">Saint Paul &amp; Minnesota Foundation<\/span><\/i><span data-contrast=\"none\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_6600\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Tammie Nasseff, CPA inactiva<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Tesorera | CFO, Neighborhood Development Center<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_6600\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/8.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Tammie Nasseff, CPA inactiva<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Tesorera | CFO, Neighborhood Development Center<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Tammie Nasseff, CPA inactiva, se desempe\u00f1a como Directora Financiera en <\/span><i><span data-contrast=\"none\">Neighborhood Development Center<\/span><\/i><span data-contrast=\"none\"> (NDC). En su rol, Tammie est\u00e1 a cargo de supervisar las finanzas de la organizaci\u00f3n y liderar al equipo de contabilidad. Cuenta con m\u00e1s de 35 a\u00f1os de experiencia en el campo contable. Antes de unirse a NDC, trabaj\u00f3 como directora financiera en <\/span><i><span data-contrast=\"none\">Rockwood Capital Management<\/span><\/i><span data-contrast=\"none\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Adem\u00e1s de haber sido contadora p\u00fablica certificada (actualmente con licencia inactiva), Tammie es asesora profesional en QuickBooks (<\/span><i><span data-contrast=\"none\">QuickBooks Pro Advisor<\/span><\/i><span data-contrast=\"none\">) y fue miembro del <\/span><i><span data-contrast=\"none\">Minnesota Board of Accountants<\/span><\/i><span data-contrast=\"none\"> y de la <\/span><i><span data-contrast=\"none\">Minnesota Board of CPAs<\/span><\/i><span data-contrast=\"none\">. Actualmente, Tammie ocupa el cargo de tesorera en las juntas directivas de <\/span><i><span data-contrast=\"none\">Esperanza United<\/span><\/i><span data-contrast=\"none\"> y de la asociaci\u00f3n de viviendas <\/span><i><span data-contrast=\"none\">Savana Townhome Associations<\/span><\/i><span data-contrast=\"none\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_6597\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Caroline Bettinger-L\u00f3pez, Ph.D.<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Professor of Law, Faculty Chair of the Human Rights Program, and Director of the Human Rights Clinic at University of Miami School of Law<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_6597\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Caroline Bettinger-L\u00f3pez, Ph.D.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Professor of Law, Faculty Chair of the Human Rights Program, and Director of the Human Rights Clinic at University of Miami School of Law<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Caroline Bettinger-L\u00f3pez, Ph.D. es profesora de Derecho, presidenta del Programa de Derechos Humanos y directora de la Cl\u00ednica de Derechos Humanos en la Facultad de Derecho de la Universidad de Miami, la cual fund\u00f3 en 2011. Entre 2022 y 2024, se desempe\u00f1\u00f3 como asesora principal sobre G\u00e9nero e Igualdad en la Oficina para las V\u00edctimas del Crimen del Departamento de Justicia de los EE. UU., donde ayud\u00f3 a liderar el desarrollo del primer Plan Nacional para Poner Fin a la Violencia de G\u00e9nero en Estados Unidos. En el oto\u00f1o de 2021, fue asesora especial del Consejo de Pol\u00edtica de G\u00e9nero de la Casa Blanca. Entre 2015 y 2017, form\u00f3 parte de la administraci\u00f3n Obama-Biden como asesora de la Casa Blanca sobre Violencia contra las Mujeres, asesora principal del vicepresidente Joe Biden y miembro del Consejo de la Casa Blanca sobre Mujeres y Ni\u00f1as.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Durante las \u00faltimas dos d\u00e9cadas, Caroline ha trabajado en la defensa de los derechos humanos en foros legales y de pol\u00edticas p\u00fablicas tanto nacionales como internacionales, abordando la violencia de g\u00e9nero, la justicia racial y los derechos de las personas inmigrantes. De 2017 a 2021, fue miembro adjunta del Consejo de Relaciones Exteriores (Council on Foreign Relations), adem\u00e1s de sus responsabilidades como docente. Ha ense\u00f1ado en las facultades de Derecho de la Universidad de Chicago y de Columbia, y fue becaria Skadden en el Proyecto de Derechos de las Mujeres de la ACLU, as\u00ed como asistente judicial en una corte federal.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Actualmente es comisionada de la Comisi\u00f3n Lancet sobre Violencia de G\u00e9nero y Maltrato a Personas J\u00f3venes. Ha recibido una beca Roddenberry por su proyecto <\/span><i><span data-contrast=\"none\">COURAGE in Policing<\/span><\/i><span data-contrast=\"none\">, enfocado en mejorar la respuesta policial ante casos de violencia dom\u00e9stica y agresi\u00f3n sexual, as\u00ed como una subvenci\u00f3n del Fondo de Defensa Legal de TIME\u2019S UP para su proyecto <\/span><i><span data-contrast=\"none\">Voces Unidas<\/span><\/i><span data-contrast=\"none\">, que apoya a trabajadoras inmigrantes de bajos ingresos.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_35752\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Adam Born, MBA<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Vice President Sales Enablement, Best Buy<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_35752\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/5.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Adam Born, MBA<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Vice President Sales Enablement, Best Buy<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Adam Born, MBA<span data-contrast=\"none\"> es un ejecutivo visionario con m\u00e1s de dos d\u00e9cadas de experiencia en liderazgo, abarcando estrategia de ventas, experiencia del cliente y transformaci\u00f3n empresarial. Reconocido por construir equipos de alto rendimiento y por implementar estrategias audaces centradas en el cliente, Adam est\u00e1 comprometido con crear experiencias significativas que generen resultados de negocio y fomenten la lealtad a largo plazo.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Actualmente se desempe\u00f1a como Vicepresidente de Habilitaci\u00f3n de Ventas en Best Buy, donde lidera las estrategias de ventas y de interacci\u00f3n con el cliente, las experiencias de dise\u00f1o premium y los programas minoristas en las plataformas f\u00edsicas y digitales de la compa\u00f1\u00eda. Su trabajo se basa en la convicci\u00f3n de que comprender a las personas \u2013tanto a los clientes como a los empleados\u2013 es la clave para un crecimiento sostenible.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_35744\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-768x768.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-768x768.png 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-300x300.png 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-150x150.png 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-600x600.png 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-100x100.png 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques.png 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Jacques Hebert<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Communications Director, McKnight Foundation<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_35744\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-768x768.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-768x768.png 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-300x300.png 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-150x150.png 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-600x600.png 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques-100x100.png 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/07\/jaques.png 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Jacques Hebert<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Communications Director, McKnight Foundation<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Jacques Hebert forma parte del Equipo Ejecutivo de Liderazgo de la <\/span><i><span data-contrast=\"none\">McKnight Foundation<\/span><\/i><span data-contrast=\"none\"> y lidera las estrategias de comunicaci\u00f3n de la organizaci\u00f3n. Desde que se uni\u00f3 a McKnight en 2022, ha dirigido con visi\u00f3n, cuidado e impacto las estrategias de comunicaci\u00f3n a nivel institucional. Bajo su liderazgo, el equipo de comunicaciones ha desempe\u00f1ado un papel clave en c\u00f3mo la fundaci\u00f3n comparte su historia, se conecta con aliados y amplifica el trabajo de quienes promueven la justicia, la equidad y soluciones clim\u00e1ticas en nuestras comunidades.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Jacques cuenta con casi dos d\u00e9cadas de experiencia en comunicaci\u00f3n, relaciones p\u00fablicas, asuntos p\u00fablicos, mercadeo y publicidad, en sectores corporativos, sin fines de lucro y filantr\u00f3picos. Su carrera abarca desde grandes empresas tecnol\u00f3gicas hasta organizaciones de medios sin fines de lucro, ONG ambientales e instituciones filantr\u00f3picas.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_22335\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-768x768.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-768x768.png 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-300x300.png 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-150x150.png 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-600x600.png 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-100x100.png 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise.png 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Marylouise Kelley, Ph.D.<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Director, Retired, Family Violence Prevention & Services, U.S. Dept. of Health and Human Services<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_22335\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-768x768.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-768x768.png 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-300x300.png 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-150x150.png 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-600x600.png 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise-100x100.png 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2022\/09\/marylouise.png 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Marylouise Kelley, Ph.D.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Director, Retired, Family Violence Prevention & Services, U.S. Dept. of Health and Human Services<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Marylouise Kelley, Ph.D. ha dedicado su carrera \u2014a nivel local y nacional\u2014 a la defensa de las personas sobrevivientes de violencia dom\u00e9stica, agresi\u00f3n sexual y maltrato infantil. Como exdirectora del <\/span><i><span data-contrast=\"none\">Family Violence Prevention and Services Program<\/span><\/i><span data-contrast=\"none\"> del Departamento de Salud y Servicios Humanos de los EE. UU., supervis\u00f3 la principal fuente de financiamiento federal para refugios de violencia dom\u00e9stica, servicios de apoyo y asistencia t\u00e9cnica.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Fue clave en la coordinaci\u00f3n de m\u00faltiples colaboraciones interinstitucionales enfocadas en temas como vivienda para v\u00edctimas de violencia dom\u00e9stica, servicios con enfoque en trauma, respuestas del sistema de salud ante la violencia sexual y de pareja, y apoyos para madres sobrevivientes y sus hijxs.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Obtuvo su doctorado en Trabajo Social en la Catholic University of America. Su disertaci\u00f3n se enfoc\u00f3 en <\/span><i><span data-contrast=\"none\">\u201cLas preocupaciones por lxs hijxs como factor en la toma de decisiones de madres sobrevivientes de violencia\u201d<\/span><\/i><span data-contrast=\"none\"> (2003).<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_38222\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Jennifer Mondino<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Directora Senior del TIME\u2019S UP Legal Defense Fund en el National Women\u2019s Law Center (NWLC)<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_38222\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/10\/Board-headshots-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Jennifer Mondino<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Directora Senior del TIME\u2019S UP Legal Defense Fund en el National Women\u2019s Law Center (NWLC)<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Jennifer Mondino es la Directora Senior del <i>TIME\u2019S UP Legal Defense Fund<\/i> en el <i>National Women\u2019s Law Center (NWLC)<\/i>. Durante m\u00e1s de 20 a\u00f1os, su carrera legal se ha enfocado en los derechos civiles y los derechos de las mujeres, con especial \u00e9nfasis en la defensa legal de personas inmigrantes y sobrevivientes de violencia dom\u00e9stica y sexual. Es una voz reconocida en temas de acoso sexual en el lugar de trabajo y justicia para sobrevivientes, y ha sido entrevistada por medios como <i>The New Yorker, Washington Post, Forbes, BBC, The Guardian<\/i> y <i>Univision.<\/i><\/p>\n<p>Antes de unirse al NWLC en 2018, Jennifer fue Abogada Principal en la Divisi\u00f3n de derechos civiles del Departamento de justicia de los Estados Unidos, donde su trabajo se centr\u00f3 en investigaciones sobre patrones o pr\u00e1cticas de violaciones de derechos civiles por parte de departamentos y agencias de seguridad p\u00fablica. Dirigi\u00f3 la primera investigaci\u00f3n de este tipo en la historia del Departamento de justicia, centrada en la respuesta policial a casos de agresi\u00f3n sexual en Missoula, Montana, y tuvo un papel clave en la redacci\u00f3n de la \u201cGu\u00eda del Departamento de justicia de 2015 sobre la prevenci\u00f3n del sesgo de g\u00e9nero en la respuesta policial a casos de agresi\u00f3n sexual y violencia dom\u00e9stica.\u201d<\/p>\n<p>Durante su tiempo en el Departamento de justicia, Jennifer tambi\u00e9n trabaj\u00f3 un a\u00f1o como asesora legal en la Oficina sobre la violencia contra las mujeres (OVW por sus signos en ingl\u00e9s), donde brind\u00f3 asesoramiento en pol\u00edticas al Departamento y apoyo jur\u00eddico a la OVW y sus beneficiarios.<\/p>\n<p>Su experiencia profesional previa incluye trabajo en el <i>Center for Reproductive Rights<\/i>, la <i>Civil Rights Bureau<\/i> de la Oficina del fiscal general del Estado de Nueva York, el <i>Safe Horizon Domestic Violence Law Project<\/i> y el bufete Mayer Brown LLP. Obtuvo su licenciatura en la Universidad de Virginia y su doctorado en derecho en la Facultad de derecho de la Universidad de Nueva York (NYU).<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_6595\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Olga Otero-Brown<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Vice President, Talent Partner and Head of Inclusive Diversity, Allstate Insurance Company<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_6595\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-768x768.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-300x300.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-150x150.jpg 150w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-600x600.jpg 600w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7-100x100.jpg 100w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2021\/08\/7.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Olga Otero-Brown<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Vice President, Talent Partner and Head of Inclusive Diversity, Allstate Insurance Company<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Como vicepresidenta de Recursos Humanos, asesora principal de talento y directora de Diversidad Inclusiva en Allstate, <\/span>Olga Otero-Brown<span data-contrast=\"none\"> lidera un equipo de alto rendimiento que impulsa relaciones estrat\u00e9gicas con clientes y ofrece soluciones de alto impacto. Su liderazgo promueve el crecimiento y la colaboraci\u00f3n, asegurando el \u00e9xito en un entorno empresarial en constante evoluci\u00f3n. Su enfoque est\u00e1 en crear una cultura inclusiva donde lxs empleadxs puedan crecer, innovar y alcanzar el \u00e9xito juntxs.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Olga se destaca por dise\u00f1ar y ejecutar estrategias que fomentan el desarrollo del talento y el crecimiento organizacional. Ha liderado procesos de transformaci\u00f3n cultural, creando ambientes inclusivos que involucran y empoderan al personal. Su pasi\u00f3n por construir conexiones significativas fortalece la efectividad de los equipos y promueve una cultura de pertenencia.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">M\u00e1s all\u00e1 de sus logros profesionales, Olga demuestra su compromiso con la comunidad a trav\u00e9s de su servicio en la Junta Directiva de <\/span><i><span data-contrast=\"none\">Esperanza United<\/span><\/i><span data-contrast=\"none\">, buscando generar un impacto positivo en las comunidades a las que sirve.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Olga tiene una licenciatura de <\/span><i><span data-contrast=\"none\">Eckerd College<\/span><\/i><span data-contrast=\"none\"> en Recursos Humanos y Literatura Espa\u00f1ola, y un MBA de <\/span><i><span data-contrast=\"none\">Lake Forest Graduate School of Management<\/span><\/i><span data-contrast=\"none\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t  \t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col-md-4 our-meet-team-post\" data-toggle=\"modal\" data-target=\"#people_39658\">\n\t\t\t\t\t\t\t\t<div class=\"meet-team-img\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"695\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-768x695.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-768x695.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-300x271.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-1024x926.jpg 1024w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-1536x1390.jpg 1536w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-2048x1853.jpg 2048w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-600x543.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"team-detail our-people\">\n\t\t\t\t\t\t\t\t\t<div class=\"team-title\">Rudy Rodriguez<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"team-position\">Exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial<\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"our-people\">\n\t\t\t\t\t\t\t\t<div class=\"modal fade\" id=\"people_39658\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"RequestRTTitle\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t  <div class=\"modal-dialog modal-xl modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"modal-header\">\n\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t  <span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  <div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"695\" src=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-768x695.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-768x695.jpg 768w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-300x271.jpg 300w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-1024x926.jpg 1024w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-1536x1390.jpg 1536w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-2048x1853.jpg 2048w, https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-600x543.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-8 people-detail\">\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title \">Rudy Rodriguez<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"position \">Exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"people-description \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p data-start=\"92\" data-end=\"523\">Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial, donde lider\u00f3 los esfuerzos de la organizaci\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\u00e1s de 20 a\u00f1os de experiencia en m\u00faltiples industrias, incluyendo Chicago Tribune, Unilever, British Petroleum, General Mills y MillerCoors.<\/p>\n<p data-start=\"525\" data-end=\"921\">Rudy ha formado parte de diversas juntas y consejos directivos, entre ellos el Mosaic Diversity Council de la American Advertising Federation, la Junta Asesora Hispana de Florida State University, el Immigrant Law Center of Minnesota, LatinoLEAD y la Junta Directiva del sistema de Minnesota State Colleges and Universities. Actualmente, forma parte de la junta del Nellie Stone Scholarship Fund.<\/p>\n<p data-start=\"923\" data-end=\"1177\" data-is-last-node=\"\" data-is-only-node=\"\">Rudy obtuvo una licenciatura en Econom\u00eda de la University of Illinois Chicago y una maestr\u00eda en Administraci\u00f3n de Empresas (MBA) de la Kellogg School of Management de Northwestern University. Reside en Minnesota junto a su esposa, Katie, y sus dos hijas.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t       \n\t\t\t\t\t<\/div>  \n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>  \n\t\t\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9d09efc\" data-id=\"9d09efc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2556064 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2556064\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef1920c\" data-id=\"ef1920c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44fb71a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"44fb71a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3954b4\" data-id=\"d3954b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-76d6e9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76d6e9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a3c5440\" data-id=\"a3c5440\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-814ed8a montserrat-sub-title elementor-widget elementor-widget-heading\" data-id=\"814ed8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span data-teams=\"true\">Aviso legal<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3570d2 training-text elementor-widget elementor-widget-heading\" data-id=\"b3570d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><span data-teams=\"true\">Esta p\u00e1gina web fue desarrollada con fondos privados. Las opiniones, hallazgos, conclusiones y recomendaciones expresadas aqu\u00ed son propias y no reflejan necesariamente los puntos de vista de ninguno de nuestros financiadores.<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Como organizaci\u00f3n latina, fundamentamos nuestro trabajo en escuchar a nuestras comunidades. Es un honor destacar la belleza, fortalezas y sabidur\u00eda de nuestra gente en este camino para poner fin a la violencia dom\u00e9stica, la agresi\u00f3n sexual, la violencia en el noviazgo y el acecho. Tambi\u00e9n valoramos a nuestr@s aliad@s que nos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4427,"parent":4425,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"template\/only-footer-page.php","meta":{"_cbd_carousel_blocks":"[]","footnotes":""},"class_list":["post-4994","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial, donde lider\u00f3 los esfuerzos de la organizaci\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\u00e1s de 20 a\u00f1os de experiencia en m\u00faltiples industrias, incluyendo Chicago Tribune, Unilever,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Rudy Rodriguez - Esperanza United\" \/>\n\t\t<meta property=\"og:description\" content=\"Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial, donde lider\u00f3 los esfuerzos de la organizaci\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\u00e1s de 20 a\u00f1os de experiencia en m\u00faltiples industrias, incluyendo Chicago Tribune, Unilever,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2316\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-12T23:40:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-24T16:08:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Rudy Rodriguez - Esperanza United\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial, donde lider\u00f3 los esfuerzos de la organizaci\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\u00e1s de 20 a\u00f1os de experiencia en m\u00faltiples industrias, incluyendo Chicago Tribune, Unilever,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/our_people\\\/rudy-rodriguez\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/sobre-nosotras\\\/#listItem\",\"name\":\"Sobre nosotr@s\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/sobre-nosotras\\\/#listItem\",\"position\":2,\"name\":\"Sobre nosotr@s\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/sobre-nosotras\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/sobre-nosotras\\\/nuestra-gente\\\/#listItem\",\"name\":\"Nuestra gente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/sobre-nosotras\\\/nuestra-gente\\\/#listItem\",\"position\":3,\"name\":\"Nuestra gente\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/sobre-nosotras\\\/#listItem\",\"name\":\"Sobre nosotr@s\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/our_people\\\/rudy-rodriguez\\\/#webpage\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/our_people\\\/rudy-rodriguez\\\/\",\"name\":\"Rudy Rodriguez - Esperanza United\",\"description\":\"Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\\u00f3n de Ameriprise Financial, donde lider\\u00f3 los esfuerzos de la organizaci\\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\\u00e1s de 20 a\\u00f1os de experiencia en m\\u00faltiples industrias, incluyendo Chicago Tribune, Unilever,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/our_people\\\/rudy-rodriguez\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Rudy-Rodriguez-199x180-1-scaled.jpg\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/our_people\\\/rudy-rodriguez\\\/#mainImage\",\"width\":2560,\"height\":2316},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/our_people\\\/rudy-rodriguez\\\/#mainImage\"},\"datePublished\":\"2026-06-12T18:40:13-05:00\",\"dateModified\":\"2026-06-24T11:08:08-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Rudy Rodriguez - Esperanza United","description":"Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial, donde lider\u00f3 los esfuerzos de la organizaci\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\u00e1s de 20 a\u00f1os de experiencia en m\u00faltiples industrias, incluyendo Chicago Tribune, Unilever,","canonical_url":"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/esperanzaunited.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/#listItem","name":"Sobre nosotr@s"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/#listItem","position":2,"name":"Sobre nosotr@s","item":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/nuestra-gente\/#listItem","name":"Nuestra gente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/nuestra-gente\/#listItem","position":3,"name":"Nuestra gente","previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/#listItem","name":"Sobre nosotr@s"}}]},{"@type":"Organization","@id":"https:\/\/esperanzaunited.org\/es\/#organization","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","url":"https:\/\/esperanzaunited.org\/es\/"},{"@type":"WebPage","@id":"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/#webpage","url":"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/","name":"Rudy Rodriguez - Esperanza United","description":"Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial, donde lider\u00f3 los esfuerzos de la organizaci\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\u00e1s de 20 a\u00f1os de experiencia en m\u00faltiples industrias, incluyendo Chicago Tribune, Unilever,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-scaled.jpg","@id":"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/#mainImage","width":2560,"height":2316},"primaryImageOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/#mainImage"},"datePublished":"2026-06-12T18:40:13-05:00","dateModified":"2026-06-24T11:08:08-05:00"},{"@type":"WebSite","@id":"https:\/\/esperanzaunited.org\/es\/#website","url":"https:\/\/esperanzaunited.org\/es\/","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","inLanguage":"es-ES","publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence","og:type":"article","og:title":"Rudy Rodriguez - Esperanza United","og:description":"Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial, donde lider\u00f3 los esfuerzos de la organizaci\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\u00e1s de 20 a\u00f1os de experiencia en m\u00faltiples industrias, incluyendo Chicago Tribune, Unilever,","og:url":"https:\/\/esperanzaunited.org\/es\/our_people\/rudy-rodriguez\/","og:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-scaled.jpg","og:image:secure_url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-scaled.jpg","og:image:width":2560,"og:image:height":2316,"article:published_time":"2026-06-12T23:40:13+00:00","article:modified_time":"2026-06-24T16:08:08+00:00","twitter:card":"summary","twitter:title":"Rudy Rodriguez - Esperanza United","twitter:description":"Rudy es exvicepresidente de Diversidad, Equidad e Inclusi\u00f3n de Ameriprise Financial, donde lider\u00f3 los esfuerzos de la organizaci\u00f3n para promover un entorno laboral diverso e inclusivo. Es un ejecutivo senior de marketing innovador y con una destacada trayectoria profesional, que cuenta con m\u00e1s de 20 a\u00f1os de experiencia en m\u00faltiples industrias, incluyendo Chicago Tribune, Unilever,","twitter:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/06\/Rudy-Rodriguez-199x180-1-scaled.jpg"},"aioseo_meta_data":{"post_id":"4994","title":null,"description":"#post_content #post_content #separator_sa","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-63e68352e737a","slug":"web-page","graphName":"WebPage","label":"P\u00e1gina web","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-08-03 23:20:31","updated":"2025-11-22 04:25:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/\" title=\"Sobre nosotr@s\">Sobre nosotr@s<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNuestra gente\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esperanzaunited.org\/es\/"},{"label":"Sobre nosotr@s","link":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/"},{"label":"Nuestra gente","link":"https:\/\/esperanzaunited.org\/es\/sobre-nosotras\/nuestra-gente\/"}],"_links":{"self":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/pages\/4994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/comments?post=4994"}],"version-history":[{"count":36,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/pages\/4994\/revisions"}],"predecessor-version":[{"id":37162,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/pages\/4994\/revisions\/37162"}],"up":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/pages\/4425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media\/4427"}],"wp:attachment":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media?parent=4994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}