
{"id":38529,"date":"2025-11-12T06:00:00","date_gmt":"2025-11-12T11:00:00","guid":{"rendered":"https:\/\/esperanzaunited.org\/?p=38529"},"modified":"2025-11-13T11:45:14","modified_gmt":"2025-11-13T16:45:14","slug":"liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2","status":"publish","type":"post","link":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/","title":{"rendered":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Patricia Torres Ray"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"38529\" class=\"elementor elementor-38529 elementor-38527\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0763540 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0763540\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb951c2\" data-id=\"bb951c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be4514b elementor-widget elementor-widget-text-editor\" data-id=\"be4514b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><span data-contrast=\"none\">En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales.\u00a0<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><i><span data-contrast=\"none\">Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, <a href=\"https:\/\/esperanzaunited.org\/es\/our_people\/vivian\/\">Vivian Huelgo, J.D.<\/a> est\u00e1 entrevistando a intercesor@s en los campos de la prevenci\u00f3n de la violencia de g\u00e9nero, el empoderamiento latino y m\u00e1s all\u00e1. Sigue leyendo para aprender lecciones de liderazgo, celebrar a las personas que realizan este trabajo y compartir nuestra gratitud por nuestra vibrante comunidad.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><i><span data-contrast=\"none\">En esta edici\u00f3n, Vivian conversa con <\/span><\/i><a href=\"https:\/\/senatedfl.mn\/home\/members\/senator-patricia-torres-ray\/\"><b><i><span data-contrast=\"none\">Patricia Torres Ray<\/span><\/i><\/b><\/a><i><span data-contrast=\"none\">, la primera latina elegida para el Senado de Minnesota y una l\u00edder comunitaria que ha dedicado m\u00e1s de 35 a\u00f1os al servicio p\u00fablico en nuestro estado.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Vivian Huelgo:<\/span><\/b><span data-contrast=\"none\"> Hola Patricia, me alegra mucho que participes hoy en <\/span><i><span data-contrast=\"none\">Liderazgo en Comunidad<\/span><\/i><span data-contrast=\"none\">. Como sabes, uno de los valores de Esperanza United es el liderazgo de las latinas. \u00bfQu\u00e9 significa para ti el liderazgo latina?<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Patricia Torres Ray:<\/span><\/b><span data-contrast=\"none\"> Para m\u00ed, el liderazgo significa la capacidad de usar nuestros talentos, nuestra presencia, nuestros recursos y nuestra influencia para tomar acciones que beneficien a la comunidad, abran caminos de oportunidad para otras personas y ayuden a proteger el planeta.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Vivian Huelgo:<\/span><\/b><span data-contrast=\"none\"> \u00bfQui\u00e9n inspir\u00f3 tu camino de liderazgo y c\u00f3mo te form\u00f3?<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Patricia Torres Ray:<\/span><\/b><span data-contrast=\"none\"> Mi camino estuvo profundamente influenciado por trabajador@s de protecci\u00f3n infantil comprometid@s con la defensa contra las desigualdades econ\u00f3micas, sociales y raciales en Minnesota. Su mentor\u00eda me permiti\u00f3 comprender mejor el contexto hist\u00f3rico y la complejidad de los desaf\u00edos que enfrentan las comunidades ind\u00edgenas, afroamericanas y otras comunidades de color.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Como inmigrante reci\u00e9n llegada, al principio me faltaba formaci\u00f3n y entendimiento de estas inequidades hist\u00f3ricas. Gracias a su gu\u00eda, entend\u00ed que aunque Minnesota muestra altos indicadores de calidad de vida, una mirada m\u00e1s cercana revela una realidad muy distinta: desigualdades profundas que siguen marcando las oportunidades y los resultados para estas comunidades.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Vivian Huelgo:<\/span><\/b><span data-contrast=\"none\"> Admiro eso en ti. Cu\u00e9ntame, \u00bfc\u00f3mo te mantienes innovadora y motivada en tu trabajo?<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Patricia Torres Ray:<\/span><\/b><span data-contrast=\"none\"> Me mantengo conectada directamente con las comunidades, sin esperar invitaci\u00f3n, participando en la vida cotidiana y en actos de resistencia local. La urgencia del momento pol\u00edtico actual me impulsa a dedicar m\u00e1s tiempo a acciones significativas en el nivel comunitario.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Tambi\u00e9n encuentro inspiraci\u00f3n en l@s j\u00f3venes comprometid@s con la justicia social. Su resiliencia, especialmente entre quienes no tienen estatus legal, es una muestra poderosa de la lucha constante por los derechos humanos fundamentales.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Vivian Huelgo:<\/span><\/b><span data-contrast=\"none\"> Muy cierto. \u00bfCu\u00e1l es una lecci\u00f3n reciente que te sorprendi\u00f3?<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Patricia Torres Ray:<\/span><\/b><span data-contrast=\"none\"> Me entristeci\u00f3 y me sorprendi\u00f3 enterarme de que, aunque much@s inmigrantes con recursos limitados han logrado grandes avances, este progreso a veces est\u00e1 generando opiniones negativas hacia nuev@s inmigrantes.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Es impactante ver c\u00f3mo algun@s inmigrantes desean restringir la llegada de otr@s, motivad@s m\u00e1s por proteger las limitadas oportunidades que han recibido que por extender la generosidad.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Vivian Huelgo:<\/span><\/b><span data-contrast=\"none\"> La gratitud es fundamental. Cu\u00e9ntame, \u00bfpor qu\u00e9 te sientes agradecida?<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"none\">Patricia Torres Ray:<\/span><\/b><span data-contrast=\"none\"> Estoy profundamente agradecida por mi familia y por las conexiones que he construido en la comunidad de Minnesota. Como inmigrante, crear una red de apoyo al llegar fue un desaf\u00edo, pero tambi\u00e9n una gran recompensa. La gente solidaria que me rodea me inspira todos los d\u00edas, y agradezco inmensamente los lazos que hemos formado.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><h3><b><span data-contrast=\"none\">M\u00e1s sobre Patricia Torres Ray<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;335559738&quot;:281,&quot;335559739&quot;:281}\">\u00a0<\/span><\/h3><p><span data-contrast=\"none\">Patricia Torres Ray, conocida cari\u00f1osamente como <\/span><i><span data-contrast=\"none\">La Senadora<\/span><\/i><span data-contrast=\"none\"> o \u201cPTR\u201d por quienes han trabajado de cerca con ella, ha dedicado m\u00e1s de 35 a\u00f1os al servicio p\u00fablico en Minnesota.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Originaria de Colombia, se mud\u00f3 a Minnesota a mediados de los a\u00f1os 80 despu\u00e9s de casarse con su esposo, Jack Ray. Al principio trabaj\u00f3 en f\u00e1bricas, pero pronto centr\u00f3 su energ\u00eda en aprender ingl\u00e9s y en acercarse a la comunidad en su nuevo pa\u00eds. En ese tiempo, form\u00f3 lazos estrechos con trabajador@s sociales ind\u00edgenas, afroamerican@s y latin@s que lideraban el movimiento de preservaci\u00f3n familiar en Minnesota. Patricia atribuye su \u00e9xito profesional y su pasi\u00f3n por la justicia social a la mentor\u00eda que recibi\u00f3 de ell@s.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Despu\u00e9s de m\u00faltiples trabajos voluntarios, incluido el programa Guardian Ad-litem en el condado de Hennepin, fue contratada como la primera <\/span><i><span data-contrast=\"none\">Ombudsperson for Families<\/span><\/i><span data-contrast=\"none\"> del estado, cargo que ayud\u00f3 a crear para proteger los derechos de l@s ni\u00f1@s en el sistema de protecci\u00f3n infantil. Tras siete a\u00f1os en ese puesto, fue contratada por el Departamento de Servicios Humanos para liderar la iniciativa <\/span><i><span data-contrast=\"none\">Children of Color<\/span><\/i><span data-contrast=\"none\">, incorporando la justicia social y la competencia cultural en servicios sociales, justicia juvenil y educaci\u00f3n temprana.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">En 2006, se postul\u00f3 para el Senado y se convirti\u00f3 en la primera latina electa en la historia de Minnesota. Durante sus 16 a\u00f1os en el cargo, promovi\u00f3 pol\u00edticas para reducir desigualdades en salud, educaci\u00f3n, vivienda, medio ambiente, transporte y desarrollo econ\u00f3mico, impulsando leyes clave para proteger a comunidades hist\u00f3ricamente marginadas.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Fue tambi\u00e9n la primera mujer de color en postularse como teniente gobernadora junto al senador John Marty, y fund\u00f3 la <\/span><a href=\"https:\/\/nhcsl.org\/media\/news\/latinas_lead_holds_1st_leadership_academy_at_rutgers\/\"><b><span data-contrast=\"none\">National Latinas Lead Academy<\/span><\/b><\/a><span data-contrast=\"none\">, apoyando y formando a l\u00edderes latin@s en todo el pa\u00eds.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Patricia ha sido reconocida a nivel local y nacional con m\u00faltiples premios, entre ellos el prestigioso <\/span><a href=\"https:\/\/www.hhh.umn.edu\/news\/joan-and-walter-mondale-commons-honors-mighty-team-who-redefined-public-service\"><b><span data-contrast=\"none\">Premio Joan y Walter Mondale de Liderazgo<\/span><\/b><\/a><span data-contrast=\"none\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">En 2022 decidi\u00f3 no buscar la reelecci\u00f3n y abri\u00f3 su propia firma, <\/span><b><span data-contrast=\"none\">PTR Associates<\/span><\/b><span data-contrast=\"none\">, para apoyar a organizaciones peque\u00f1as en el desarrollo de estrategias pol\u00edticas y de incidencia p\u00fablica centradas en las comunidades ind\u00edgenas, inmigrantes y de color. Patricia es egresada de la <\/span><i><span data-contrast=\"none\">Humphrey School of Public Affairs<\/span><\/i><span data-contrast=\"none\"> de la Universidad de Minnesota y madre de dos hijos, Tom\u00e1s y Patrick.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales.\u00a0\u00a0 Para avanzar en este enfoque basado [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":38508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_cbd_carousel_blocks":"[]","footnotes":""},"categories":[107,468],"tags":[100,102,99,103,176],"class_list":["post-38529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","category-blog-es-2","tag-apoyo-a-las-familias","tag-entrenamientos-y-asistencia-tecnica","tag-gratis","tag-investigacion-y-evaluacion","tag-prevencion"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"dsullivan@casadeesperanza.org\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United\" \/>\n\t\t<meta property=\"og:description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/11\/10.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/11\/10.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-12T11:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-13T16:45:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/11\/10.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#blogposting\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United\",\"headline\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Patricia Torres Ray\",\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/10.jpg\",\"width\":640,\"height\":400},\"datePublished\":\"2025-11-12T06:00:00-05:00\",\"dateModified\":\"2025-11-13T11:45:14-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#webpage\"},\"articleSection\":\"Blog, Blog, Apoyo a las familias, Entrenamientos y asistencia t\\u00e9cnica, Gratis, Investigaci\\u00f3n y evaluaci\\u00f3n, Prevenci\\u00f3n, Optional, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/category\\\/blog-es\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/category\\\/blog-es\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/category\\\/blog-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#listItem\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Patricia Torres Ray\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#listItem\",\"position\":3,\"name\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Patricia Torres Ray\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/category\\\/blog-es\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/\",\"name\":\"dsullivan@casadeesperanza.org\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21c9f1483d8a4dea4829e460b61ff9ace90e41bba353ea78349096b86a29f419?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"dsullivan@casadeesperanza.org\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#webpage\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United\",\"description\":\"En Esperanza United, sabemos que ninguna organizaci\\u00f3n ni persona, por s\\u00ed sola, va a erradicar la violencia de g\\u00e9nero \\u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/10.jpg\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#mainImage\",\"width\":640,\"height\":400},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\\\/#mainImage\"},\"datePublished\":\"2025-11-12T06:00:00-05:00\",\"dateModified\":\"2025-11-13T11:45:14-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United","description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta","canonical_url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#blogposting","name":"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United","headline":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Patricia Torres Ray","author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/11\/10.jpg","width":640,"height":400},"datePublished":"2025-11-12T06:00:00-05:00","dateModified":"2025-11-13T11:45:14-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#webpage"},"isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#webpage"},"articleSection":"Blog, Blog, Apoyo a las familias, Entrenamientos y asistencia t\u00e9cnica, Gratis, Investigaci\u00f3n y evaluaci\u00f3n, Prevenci\u00f3n, Optional, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/esperanzaunited.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/#listItem","position":2,"name":"Blog","item":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#listItem","name":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Patricia Torres Ray"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#listItem","position":3,"name":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Patricia Torres Ray","previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/esperanzaunited.org\/es\/#organization","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","url":"https:\/\/esperanzaunited.org\/es\/"},{"@type":"Person","@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author","url":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/","name":"dsullivan@casadeesperanza.org","image":{"@type":"ImageObject","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/21c9f1483d8a4dea4829e460b61ff9ace90e41bba353ea78349096b86a29f419?s=96&d=mm&r=g","width":96,"height":96,"caption":"dsullivan@casadeesperanza.org"}},{"@type":"WebPage","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#webpage","url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/","name":"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United","description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#breadcrumblist"},"author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"creator":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/11\/10.jpg","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#mainImage","width":640,"height":400},"primaryImageOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/#mainImage"},"datePublished":"2025-11-12T06:00:00-05:00","dateModified":"2025-11-13T11:45:14-05:00"},{"@type":"WebSite","@id":"https:\/\/esperanzaunited.org\/es\/#website","url":"https:\/\/esperanzaunited.org\/es\/","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","inLanguage":"es-ES","publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence","og:type":"article","og:title":"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United","og:description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta","og:url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/","og:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/11\/10.jpg","og:image:secure_url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/11\/10.jpg","og:image:width":640,"og:image:height":400,"article:published_time":"2025-11-12T11:00:00+00:00","article:modified_time":"2025-11-13T16:45:14+00:00","twitter:card":"summary","twitter:title":"Liderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray - Esperanza United","twitter:description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta","twitter:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2025\/11\/10.jpg"},"aioseo_meta_data":{"post_id":"38529","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-11-09 03:59:09","updated":"2025-11-22 04:33:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLiderazgo en comunidad con Vivian Huelgo y Patricia Torres Ray\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esperanzaunited.org\/es\/"},{"label":"Blog","link":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/"},{"label":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Patricia Torres Ray","link":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-patricia-torres-ray-2\/"}],"_links":{"self":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/38529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/comments?post=38529"}],"version-history":[{"count":1,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/38529\/revisions"}],"predecessor-version":[{"id":38541,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/38529\/revisions\/38541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media\/38508"}],"wp:attachment":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media?parent=38529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/categories?post=38529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/tags?post=38529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}