
{"id":39501,"date":"2026-05-04T13:14:56","date_gmt":"2026-05-04T18:14:56","guid":{"rendered":"https:\/\/esperanzaunited.org\/?p=39501"},"modified":"2026-05-05T13:19:12","modified_gmt":"2026-05-05T18:19:12","slug":"liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon","status":"publish","type":"post","link":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/","title":{"rendered":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Maria Pabon"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"39501\" class=\"elementor elementor-39501\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0763540 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0763540\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb951c2\" data-id=\"bb951c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be4514b elementor-widget elementor-widget-text-editor\" data-id=\"be4514b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales.\u00a0<\/p><p class=\"p1\">Para\u00a0avanzar\u00a0en\u00a0este\u00a0enfoque\u00a0basado\u00a0en\u00a0fortalezas, la\u00a0Presidenta\u00a0y\u00a0Directora\u00a0ejecutiva\u00a0de Esperanza United,\u00a0<a href=\"https:\/\/esperanzaunited.org\/es\/our_people\/vivian-huelgo\/\"><span class=\"s1\"><i>Vivian Huelgo, J.D.<\/i><\/span><\/a>, est\u00e1 entrevistando a l\u00edderes en los campos de la prevenci\u00f3n de la violencia de g\u00e9nero, el empoderamiento latin@ y m\u00e1s all\u00e1. Sigue leyendo para aprender lecciones de liderazgo, celebrar a las personas que realizan este trabajo y compartir nuestra gratitud por nuestra vibrante comunidad.\u00a0<\/p><p class=\"p1\">En\u00a0esta\u00a0edici\u00f3n, Vivian conversa con\u00a0<a href=\"https:\/\/esperanzaunited.org\/es\/our_people\/maria-c-pabon-gautier\/\"><span class=\"s1\"><i>Mar\u00eda Pab\u00f3n<\/i><\/span><\/a><i>,<\/i>\u00a0Ph.D.,\u00a0Vicepresidenta\u00a0de la Junta\u00a0Directiva\u00a0de Esperanza United y\u00a0Directora\u00a0de Personas (Chief People Officer)\u00a0en\u00a0Project for Pride in Living. Pues,\u00a0vamos:\u00a0<\/p><p class=\"p1\"><b>Vivian\u00a0Huelgo:<\/b> Hola Mar\u00eda, uno de nuestros valores organizacionales es el liderazgo latino, \u00bfqu\u00e9 significa para ti el liderazgo (latino)?\u00a0<\/p><p class=\"p1\"><b>Mar\u00eda Pab\u00f3n: <\/b>Significa abrazar las fortalezas \u00fanicas que surgen de la intersecci\u00f3n de mi cultura, identidad y g\u00e9nero, y llevar esas perspectivas a espacios donde a menudo estamos subrepresentad@s. Significa ser un ejemplo que inspire a las nuevas generaciones a entender que no somos una sola historia. Tambi\u00e9n significa retribuir, invirtiendo en j\u00f3venes latinas, as\u00ed como alguien alguna vez invirti\u00f3 en m\u00ed.\u00a0<\/p><p class=\"p1\"><b>Vivian\u00a0Huelgo:<\/b>\u00a0\u00bfC\u00f3mo\u00a0apoyas\u00a0o\u00a0acompa\u00f1as\u00a0a la\u00a0pr\u00f3xima\u00a0generaci\u00f3n\u00a0de\u00a0l\u00edderes\u00a0latinas?\u00a0<\/p><p class=\"p1\"><b>Mar\u00edaPab\u00f3n:<\/b> Me tomo el tiempo de entender en qu\u00e9 momento de su camino se encuentra cada joven latina. Me veo como alguien que puede abrir puertas y luego dar un paso atr\u00e1s para que ellas construyan su propio camino. Soy orgullosamente puertorrique\u00f1a, y cuando acompa\u00f1o a j\u00f3venes latinas, me apoyo en el orgullo y la belleza de quienes somos. Somos mucho m\u00e1s que el dolor o las luchas que hemos vivido; somos resiliencia, talento y posibilidad.\u00a0<\/p><p class=\"p1\"><b>Vivian\u00a0Huelgo:<\/b>\u00a0\u00bfC\u00f3mo\u00a0mantienes\u00a0a\u00a0tu equipo motivado y conectado con la misi\u00f3n?\u00a0<\/p><p class=\"p1\"><b>Mar\u00eda Pab\u00f3n: <\/b>Mantengo nuestro \u201cpor qu\u00e9\u201d en el centro de todo lo que hacemos. El trabajo en PPL es desafiante, pero cuando estamos conectad@s con nuestro prop\u00f3sito, avanzamos como comunidad. Tambi\u00e9n me enfoco en reconocer las fortalezas \u00fanicas de cada persona del equipo y c\u00f3mo se complementan entre s\u00ed. Lidero con valores como la inclusi\u00f3n y la humildad cultural, porque cuando aprendemos y crecemos junt@s, podemos liderar desde nuestra autenticidad.\u00a0<\/p><p class=\"p1\"><b>Vivian\u00a0Huelgo:<\/b> \u00bfCu\u00e1l es una lecci\u00f3n reciente que te\u00a0sorprendi\u00f3?\u00a0<\/p><p class=\"p1\"><b>Mar\u00eda Pab\u00f3n<\/b>: Una lecci\u00f3n que a\u00fan me acompa\u00f1a ocurri\u00f3 hace algunos a\u00f1os. Me record\u00f3 que siempre hay alguien observando y aprendiendo mientras construye su propio camino de liderazgo, incluso cuando no lo sabemos.\u00a0<\/p><p class=\"p1\">Cuando llegu\u00e9 a PPL, traje mis diplomas de posgrado. No pensaba colgarlos; solo estaban entre mis cosas. Cuando el personal de mantenimiento vino a ayudar a colgar cuadros, les dije que no colgaran mis t\u00edtulos porque \u201cno eran necesarios aqu\u00ed\u201d.\u00a0<\/p><p class=\"p1\">Al d\u00eda siguiente, los vi en la pared. Cuando pregunt\u00e9 por qu\u00e9, me dijeron: \u201cNecesitamos ver a m\u00e1s personas como nosotr@s lograrlo. Hay l\u00edderes entre nosotr@s, y es importante que mostremos que tod@s podemos hacerlo.\u201d\u00a0<\/p><p class=\"p1\">Ese momento cambi\u00f3 mi perspectiva. Hasta hoy, esos diplomas siguen en mi pared, no como un logro personal, sino como una responsabilidad. Me recuerdan que la representaci\u00f3n importa y que debo liderar de una manera que inspire a otras personas.<\/p><div class=\"blog-post-title clearfix mb-4\">\u00a0<\/div><div class=\"main-post\"><div class=\"entry-content blog-detail-page border-bottom-0 text-element\"><h3 class=\"p1\"><a href=\"https:\/\/esperanzaunited.org\/es\/our_people\/maria-c-pabon-gautier-2\/\">Mar\u00eda C. Pab\u00f3n Gautier, Ph.D.<\/a><\/h3><p class=\"p1\"><strong>Vicepresidenta | Chief People Officer, Project For Pride In Living<\/strong><\/p><p class=\"p2\">La Dra. Mar\u00eda C. Pab\u00f3n Gautier\u00a0es Directora de Personas (Chief People Officer) en\u00a0Project for Pride in Living, con sede en Minneapolis, MN. En este cargo, lidera las estrategias y programas de equidad racial, recursos humanos, desarrollo de talento, administraci\u00f3n\/operaciones y la divisi\u00f3n de preparaci\u00f3n profesional. Mar\u00eda tiene un doctorado en Psicolog\u00eda Educativa de la Universidad de Minnesota y una licenciatura en Psicolog\u00eda de la Universidad de Puerto Rico. Con m\u00e1s de 20 a\u00f1os de experiencia, ha dedicado su carrera a la formaci\u00f3n, el acompa\u00f1amiento, la docencia y la investigaci\u00f3n para desarrollar pr\u00e1cticas fundamentadas en evidencia.\u00a0<\/p><p class=\"p2\">Su amplia trayectoria abarca organizaciones sin fines de lucro, instituciones de educaci\u00f3n superior, el sector privado, educaci\u00f3n K-12 y agencias gubernamentales, siempre con un enfoque en el apoyo a comunidades desatendidas y marginadas. Su trabajo se basa en un enfoque interdisciplinario y diverso, con un compromiso firme hacia la justicia, equidad, diversidad e inclusi\u00f3n (JEDI, por sus siglas en ingl\u00e9s) en diversos entornos.\u00a0<\/p><p class=\"p2\">Antes de su puesto actual, Mar\u00eda fue Vicepresidenta de Equidad e Inclusi\u00f3n en\u00a0St. Olaf College. A lo largo de su carrera, ha sido guiada por principios de compromiso comunitario, la filosof\u00eda de\u00a0\u201cpor nosotrxs, para nosotrxs\u201d\u00a0y una base s\u00f3lida en investigaci\u00f3n, medici\u00f3n y evaluaci\u00f3n.\u00a0<\/p><p class=\"p2\">Su enfoque se centra especialmente en la equidad racial y metodolog\u00edas basadas en fortalezas, asegurando que las comunidades de color est\u00e9n al centro del desarrollo y de los procesos de toma de decisiones. Su labor busca fomentar entornos inclusivos donde todas las personas puedan prosperar y contribuir de manera significativa.\u00a0<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales.\u00a0 Para\u00a0avanzar\u00a0en\u00a0este\u00a0enfoque\u00a0basado\u00a0en\u00a0fortalezas, la\u00a0Presidenta\u00a0y\u00a0Directora\u00a0ejecutiva\u00a0de Esperanza United,\u00a0Vivian Huelgo, J.D., [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":39509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_cbd_carousel_blocks":"[]","footnotes":""},"categories":[107],"tags":[100,102,99,103,176],"class_list":["post-39501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","tag-apoyo-a-las-familias","tag-entrenamientos-y-asistencia-tecnica","tag-gratis","tag-investigacion-y-evaluacion","tag-prevencion"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"dsullivan@casadeesperanza.org\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United\" \/>\n\t\t<meta property=\"og:description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/28-2.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/28-2.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-04T18:14:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-05T18:19:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/28-2.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#blogposting\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United\",\"headline\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Maria Pabon\",\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/28-2.jpg\",\"width\":1200,\"height\":628},\"datePublished\":\"2026-05-04T13:14:56-05:00\",\"dateModified\":\"2026-05-05T13:19:12-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#webpage\"},\"articleSection\":\"Blog, Apoyo a las familias, Entrenamientos y asistencia t\\u00e9cnica, Gratis, Investigaci\\u00f3n y evaluaci\\u00f3n, Prevenci\\u00f3n, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/category\\\/blog-es\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/category\\\/blog-es\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/category\\\/blog-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#listItem\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Maria Pabon\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#listItem\",\"position\":3,\"name\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Maria Pabon\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/category\\\/blog-es\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/\",\"name\":\"dsullivan@casadeesperanza.org\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21c9f1483d8a4dea4829e460b61ff9ace90e41bba353ea78349096b86a29f419?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"dsullivan@casadeesperanza.org\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#webpage\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United\",\"description\":\"En Esperanza United, sabemos que ninguna organizaci\\u00f3n ni persona, por s\\u00ed sola, va a erradicar la violencia de g\\u00e9nero \\u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\\u00e1 entrevistando a l\\u00edderes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/28-2.jpg\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#mainImage\",\"width\":1200,\"height\":628},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\\\/#mainImage\"},\"datePublished\":\"2026-05-04T13:14:56-05:00\",\"dateModified\":\"2026-05-05T13:19:12-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United","description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes","canonical_url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#blogposting","name":"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United","headline":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Maria Pabon","author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/28-2.jpg","width":1200,"height":628},"datePublished":"2026-05-04T13:14:56-05:00","dateModified":"2026-05-05T13:19:12-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#webpage"},"isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#webpage"},"articleSection":"Blog, Apoyo a las familias, Entrenamientos y asistencia t\u00e9cnica, Gratis, Investigaci\u00f3n y evaluaci\u00f3n, Prevenci\u00f3n, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/esperanzaunited.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/#listItem","position":2,"name":"Blog","item":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#listItem","name":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Maria Pabon"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#listItem","position":3,"name":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Maria Pabon","previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/esperanzaunited.org\/es\/#organization","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","url":"https:\/\/esperanzaunited.org\/es\/"},{"@type":"Person","@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author","url":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/","name":"dsullivan@casadeesperanza.org","image":{"@type":"ImageObject","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/21c9f1483d8a4dea4829e460b61ff9ace90e41bba353ea78349096b86a29f419?s=96&d=mm&r=g","width":96,"height":96,"caption":"dsullivan@casadeesperanza.org"}},{"@type":"WebPage","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#webpage","url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/","name":"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United","description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#breadcrumblist"},"author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"creator":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/28-2.jpg","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#mainImage","width":1200,"height":628},"primaryImageOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/#mainImage"},"datePublished":"2026-05-04T13:14:56-05:00","dateModified":"2026-05-05T13:19:12-05:00"},{"@type":"WebSite","@id":"https:\/\/esperanzaunited.org\/es\/#website","url":"https:\/\/esperanzaunited.org\/es\/","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","inLanguage":"es-ES","publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence","og:type":"article","og:title":"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United","og:description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes","og:url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/","og:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/28-2.jpg","og:image:secure_url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/28-2.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2026-05-04T18:14:56+00:00","article:modified_time":"2026-05-05T18:19:12+00:00","twitter:card":"summary","twitter:title":"Liderazgo en comunidad con Vivian Huelgo y Maria Pabon - Esperanza United","twitter:description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes","twitter:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/28-2.jpg"},"aioseo_meta_data":{"post_id":"39501","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-05-02 15:24:21","updated":"2026-05-05 18:27:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLiderazgo en comunidad con Vivian Huelgo y Maria Pabon\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esperanzaunited.org\/es\/"},{"label":"Blog","link":"https:\/\/esperanzaunited.org\/es\/category\/blog-es\/"},{"label":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Maria Pabon","link":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-maria-pabon\/"}],"_links":{"self":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/39501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/comments?post=39501"}],"version-history":[{"count":4,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/39501\/revisions"}],"predecessor-version":[{"id":39506,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/39501\/revisions\/39506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media\/39509"}],"wp:attachment":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media?parent=39501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/categories?post=39501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/tags?post=39501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}