
{"id":39614,"date":"2026-05-18T21:57:57","date_gmt":"2026-05-19T02:57:57","guid":{"rendered":"https:\/\/esperanzaunited.org\/?p=39614"},"modified":"2026-05-18T22:07:21","modified_gmt":"2026-05-19T03:07:21","slug":"liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez","status":"publish","type":"post","link":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/","title":{"rendered":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Linda Lopez"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"39614\" class=\"elementor elementor-39614 elementor-39601\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0763540 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0763540\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb951c2\" data-id=\"bb951c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be4514b elementor-widget elementor-widget-text-editor\" data-id=\"be4514b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales.\u00a0<\/p><p class=\"p1\">Para\u00a0avanzar\u00a0en\u00a0este\u00a0enfoque\u00a0basado\u00a0en\u00a0fortalezas, la\u00a0Presidenta\u00a0y\u00a0Directora\u00a0ejecutiva\u00a0de Esperanza United,\u00a0<a href=\"https:\/\/esperanzaunited.org\/es\/our_people\/vivian-huelgo\/\"><span class=\"s1\"><i>Vivian Huelgo, J.D.<\/i><\/span><\/a>, est\u00e1 entrevistando a l\u00edderes en los campos de la prevenci\u00f3n de la violencia de g\u00e9nero, el empoderamiento latin@ y m\u00e1s all\u00e1. Sigue leyendo para aprender lecciones de liderazgo, celebrar a las personas que realizan este trabajo y compartir nuestra gratitud por nuestra vibrante comunidad.\u00a0<\/p><p class=\"p1\">En esta edici\u00f3n, Vivian conversa con\u00a0<span class=\"s1\"><i>Linda Lopez<\/i><\/span><i>,<\/i> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW43502161 BCX0\">subdirectora<\/span><span class=\"NormalTextRun SCXW43502161 BCX0\"> del Center for Battered Women\u2019s Legal Services. <\/span>Pues,\u00a0vamos:\u00a0<\/p><p class=\"p1\"><strong>Vivian:<\/strong> \u00bfQui\u00e9n inspir\u00f3 tu camino hacia el liderazgo y c\u00f3mo influy\u00f3 en ti?\u00a0<\/p><p class=\"p1\"><b>Linda:<\/b> Mi camino hacia el liderazgo fue inspirado por las mujeres en mi vida, especialmente mi madre. Mi madre fue una de las personas m\u00e1s inteligentes que he conocido. Era la cabeza de nuestro hogar, una madre soltera de 10 hijos. Aunque ten\u00eda recursos limitados y una educaci\u00f3n limitada, era inteligente, ingeniosa, tenaz y valiente cuando se trataba de proveer y proteger a sus hijos. Ten\u00eda una fortaleza silenciosa y me ense\u00f1\u00f3 que la voz m\u00e1s fuerte no siempre es la m\u00e1s sabia.<\/p><p class=\"p1\">Tambi\u00e9n persever\u00f3 frente a grandes adversidades. Era una mujer que demostraba su amor a trav\u00e9s de sus acciones. Me ense\u00f1\u00f3 que el liderazgo se trata de ser valiente, ingeniosa y perseverante. Aprend\u00ed que el liderazgo consiste en crear oportunidades, pensar y planificar para el futuro, y que brindar oportunidades con un alto nivel de autonom\u00eda a las personas con las que trabajas siempre es lo mejor.\u00a0<\/p><p class=\"p1\"><b>Vivian:<\/b>\u00a0\u00bfC\u00f3mo\u00a0acompa\u00f1as\u00a0o\u00a0apoyas\u00a0a la\u00a0pr\u00f3xima\u00a0generaci\u00f3n\u00a0de\u00a0l\u00edderes\u00a0latinas?\u00a0<\/p><p class=\"p1\"><b>Linda:<\/b> Para m\u00ed es importante que la pr\u00f3xima generaci\u00f3n de l\u00edderes latinas entienda su valor y lo que merecen. Que se sientan empoderadas para alzar la voz sin miedo y sin disculparse. Quiero que las l\u00edderes latinas se vean a s\u00ed mismas en los niveles m\u00e1s altos de sus profesiones, que crean que merecen estar en esos espacios y que merecen ser valoradas por la sociedad. Comparto abiertamente mis experiencias y mis luchas con otras l\u00edderes latinas con la esperanza de que eso pueda ayudarlas en sus propios caminos.\u00a0<\/p><p class=\"p1\"><b>Vivian:\u00a0<\/b>\u00bfCu\u00e1l es una lecci\u00f3n que aprendiste recientemente y que te sorprendi\u00f3?\u00a0<\/p><p class=\"p1\"><b>Linda:\u00a0<\/b>No s\u00e9 si necesariamente me sorprendi\u00f3, pero s\u00ed me preocup\u00f3. He visto una disminuci\u00f3n en la cantidad de abogadas latinas que solicitan puestos en organizaciones sin fines de lucro enfocadas en violencia dom\u00e9stica y sexual, y eso realmente me entristece y preocupa.\u00a0<\/p><p class=\"p1\"><b>Vivian:\u00a0<\/b>Otro de los valores de nuestra organizaci\u00f3n es vivir libres de violencia. \u00bfC\u00f3mo se ve para ti un futuro libre de violencia?\u00a0<\/p><p class=\"p1\"><b>Linda:\u00a0<\/b>Un futuro libre de violencia es uno donde no exista una brecha salarial de g\u00e9nero, donde las personas tengan plena autonom\u00eda sobre sus cuerpos, donde se eliminen las normas de g\u00e9nero r\u00edgidas, donde las mujeres, especialmente las mujeres de color, ocupen posiciones clave en todos los \u00e1mbitos de la sociedad, y donde cada persona tenga acceso a atenci\u00f3n m\u00e9dica gratuita, cuidado infantil y vivienda asequible.\u00a0<\/p><p class=\"p1\"><b>CIERRE:\u00a0<\/b>Estoy agradecida por el privilegio y las oportunidades que me ha brindado ser abogada. Estoy agradecida por las mujeres fuertes y resilientes que contin\u00faan luchando por los derechos de todas las mujeres en este pa\u00eds y en todo el mundo, y agradecida por el amor y el apoyo de las personas en mi vida.\u00a0<\/p><div class=\"main-post\"><div class=\"entry-content blog-detail-page border-bottom-0 text-element\"><p class=\"p1\">\u00a0<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaa5fca elementor-widget elementor-widget-text-editor\" data-id=\"eaa5fca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"p1\"><span class=\"TextRun SCXW12039348 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW12039348 BCX0\">Linda Lopez, JD<\/span><\/span><\/h3><p class=\"p1\"><strong><span class=\"NormalTextRun SpellingErrorV2Themed SCXW85515862 BCX0\">Subdirectora<\/span> | <span class=\"NormalTextRun SCXW85515862 BCX0\">Center for Battered Women\u2019s Legal Services<\/span><\/strong><\/p><p class=\"p1\">Linda Lopez, JD, es subdirectora del Center for Battered Women\u2019s Legal Services. Linda Lopez comenz\u00f3 como abogada del personal en el Legal Center de Sanctuary en 1994. En 2006, se convirti\u00f3 en subdirectora del Center, donde trabaja junto a la directora para defender los derechos de sobrevivientes de violencia dom\u00e9stica y sexual.\u00a0<\/p><p class=\"p1\">La Sra. Lopez es fundadora del Uncontested Divorce Workshop, un programa a trav\u00e9s del cual capacit\u00f3 a m\u00e1s de 600 estudiantes de cinco facultades de derecho de la ciudad de Nueva York para trabajar con mujeres sobrevivientes de violencia dom\u00e9stica y de bajos recursos en la obtenci\u00f3n de divorcios no disputados. Tiene una amplia trayectoria en derecho familiar y matrimonial y es biling\u00fce en espa\u00f1ol.\u00a0<\/p><p class=\"p1\">Adem\u00e1s, supervisa el Community Law Project de Sanctuary, el cual brinda alcance comunitario, capacitaciones y representaci\u00f3n legal directa a comunidades hist\u00f3ricamente desatendidas. Es egresada de CUNY Law School, donde particip\u00f3 en la Battered Women\u2019s Clinic.\u00a0<\/p><p class=\"p1\">La Sra. Lopez ha participado en numerosos programas de televisi\u00f3n y radio tanto en espa\u00f1ol como en ingl\u00e9s. Tambi\u00e9n ha ofrecido capacitaciones extensivas sobre violencia dom\u00e9stica y sexual a nivel local, nacional e internacional, y ha formado parte de m\u00faltiples paneles, talleres y foros.\u00a0<\/p><p class=\"p1\">Form\u00f3 parte de la ABA Commission on Domestic and Sexual Violence, del Committee on the Courts de la New York City Bar Association, del Family Law Committee de la New York City Bar Association, y tambi\u00e9n particip\u00f3 como panelista en procesos de selecci\u00f3n judicial.\u00a0<\/p><p class=\"p1\">En 2011 recibi\u00f3 el NYC Bar Association Legal Services Award. En 2022 recibi\u00f3 el premio The Abely Award for Leading Women and Children to Safety, y en 2025 recibi\u00f3 el Public Service Award de la New York County Lawyers Association.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales.\u00a0 Para\u00a0avanzar\u00a0en\u00a0este\u00a0enfoque\u00a0basado\u00a0en\u00a0fortalezas, la\u00a0Presidenta\u00a0y\u00a0Directora\u00a0ejecutiva\u00a0de Esperanza United,\u00a0Vivian Huelgo, J.D., [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":39609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_cbd_carousel_blocks":"[]","footnotes":""},"categories":[32,107],"tags":[100,102,99,103,176,39],"class_list":["post-39614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-es","tag-apoyo-a-las-familias","tag-entrenamientos-y-asistencia-tecnica","tag-gratis","tag-investigacion-y-evaluacion","tag-prevencion","tag-research-and-evaluation"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"dsullivan@casadeesperanza.org\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n<\/script>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United\" \/>\n\t\t<meta property=\"og:description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/30.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/30.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-19T02:57:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-19T03:07:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/30.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#blogposting\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United\",\"headline\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Linda Lopez\",\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/30.jpg\",\"width\":1920,\"height\":1080},\"datePublished\":\"2026-05-18T21:57:57-05:00\",\"dateModified\":\"2026-05-18T22:07:21-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#webpage\"},\"articleSection\":\"Blog, Blog, Apoyo a las familias, Entrenamientos y asistencia t\\u00e9cnica, Gratis, Investigaci\\u00f3n y evaluaci\\u00f3n, Prevenci\\u00f3n, Research and evaluation, Optional, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/en\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/esperanzaunited.org\\\/en\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#listItem\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Linda Lopez\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#listItem\",\"position\":3,\"name\":\"Liderazgo en comunidad con Vivian Huelgo\\u00a0y Linda Lopez\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/\",\"name\":\"dsullivan@casadeesperanza.org\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21c9f1483d8a4dea4829e460b61ff9ace90e41bba353ea78349096b86a29f419?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"dsullivan@casadeesperanza.org\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#webpage\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/\",\"name\":\"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United\",\"description\":\"En Esperanza United, sabemos que ninguna organizaci\\u00f3n ni persona, por s\\u00ed sola, va a erradicar la violencia de g\\u00e9nero \\u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\\u00e1 entrevistando a l\\u00edderes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/author\\\/dsullivancasadeesperanza-org\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/30.jpg\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\\\/#mainImage\"},\"datePublished\":\"2026-05-18T21:57:57-05:00\",\"dateModified\":\"2026-05-18T22:07:21-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/\",\"name\":\"Esperanza United\",\"description\":\"Mobilizing Latinas and Latin@ communities to end domestic violence\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/esperanzaunited.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United","description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes","canonical_url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-SMTPZE0LGB\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-SMTPZE0LGB');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#blogposting","name":"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United","headline":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Linda Lopez","author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/30.jpg","width":1920,"height":1080},"datePublished":"2026-05-18T21:57:57-05:00","dateModified":"2026-05-18T22:07:21-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#webpage"},"isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#webpage"},"articleSection":"Blog, Blog, Apoyo a las familias, Entrenamientos y asistencia t\u00e9cnica, Gratis, Investigaci\u00f3n y evaluaci\u00f3n, Prevenci\u00f3n, Research and evaluation, Optional, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/esperanzaunited.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/en\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/en\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/esperanzaunited.org\/en\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#listItem","name":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Linda Lopez"},"previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#listItem","position":3,"name":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Linda Lopez","previousItem":{"@type":"ListItem","@id":"https:\/\/esperanzaunited.org\/en\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/esperanzaunited.org\/es\/#organization","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","url":"https:\/\/esperanzaunited.org\/es\/"},{"@type":"Person","@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author","url":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/","name":"dsullivan@casadeesperanza.org","image":{"@type":"ImageObject","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/21c9f1483d8a4dea4829e460b61ff9ace90e41bba353ea78349096b86a29f419?s=96&d=mm&r=g","width":96,"height":96,"caption":"dsullivan@casadeesperanza.org"}},{"@type":"WebPage","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#webpage","url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/","name":"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United","description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/esperanzaunited.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#breadcrumblist"},"author":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"creator":{"@id":"https:\/\/esperanzaunited.org\/es\/author\/dsullivancasadeesperanza-org\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/30.jpg","@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/#mainImage"},"datePublished":"2026-05-18T21:57:57-05:00","dateModified":"2026-05-18T22:07:21-05:00"},{"@type":"WebSite","@id":"https:\/\/esperanzaunited.org\/es\/#website","url":"https:\/\/esperanzaunited.org\/es\/","name":"Esperanza United","description":"Mobilizing Latinas and Latin@ communities to end domestic violence","inLanguage":"es-ES","publisher":{"@id":"https:\/\/esperanzaunited.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Esperanza United - Mobilizing Latinas and Latin@ communities to end domestic violence","og:type":"article","og:title":"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United","og:description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes","og:url":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/","og:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/30.jpg","og:image:secure_url":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/30.jpg","og:image:width":1920,"og:image:height":1080,"article:published_time":"2026-05-19T02:57:57+00:00","article:modified_time":"2026-05-19T03:07:21+00:00","twitter:card":"summary","twitter:title":"Liderazgo en comunidad con Vivian Huelgo y Linda Lopez - Esperanza United","twitter:description":"En Esperanza United, sabemos que ninguna organizaci\u00f3n ni persona, por s\u00ed sola, va a erradicar la violencia de g\u00e9nero \u2013 se necesita a las comunidades trabajando juntas. Por eso, el liderazgo latino y las soluciones lideradas por la comunidad son dos de nuestros valores organizacionales. Para avanzar en este enfoque basado en fortalezas, la Presidenta y Directora ejecutiva de Esperanza United, Vivian Huelgo, J.D., est\u00e1 entrevistando a l\u00edderes","twitter:image":"https:\/\/esperanzaunited.org\/wp-content\/uploads\/2026\/05\/30.jpg"},"aioseo_meta_data":{"post_id":"39614","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-05-19 02:55:54","updated":"2026-05-19 23:17:25","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/esperanzaunited.org\/en\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLiderazgo en comunidad con Vivian Huelgo y Linda Lopez\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/esperanzaunited.org\/es\/"},{"label":"Blog","link":"https:\/\/esperanzaunited.org\/en\/category\/blog\/"},{"label":"Liderazgo en comunidad con Vivian Huelgo\u00a0y Linda Lopez","link":"https:\/\/esperanzaunited.org\/es\/liderazgo-en-comunidad-con-vivian-huelgo-y-linda-lopez\/"}],"_links":{"self":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/39614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/comments?post=39614"}],"version-history":[{"count":4,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/39614\/revisions"}],"predecessor-version":[{"id":39618,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/posts\/39614\/revisions\/39618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media\/39609"}],"wp:attachment":[{"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/media?parent=39614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/categories?post=39614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esperanzaunited.org\/es\/wp-json\/wp\/v2\/tags?post=39614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}